{"id":803,"date":"2023-07-21T22:57:05","date_gmt":"2023-07-21T22:57:05","guid":{"rendered":"https:\/\/ghostwhite-loris-458768.hostingersite.com\/?page_id=803"},"modified":"2025-06-09T10:28:09","modified_gmt":"2025-06-09T10:28:09","slug":"home-cz","status":"publish","type":"page","link":"https:\/\/portalinv.org\/cs\/","title":{"rendered":"Domov"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"803\" class=\"elementor elementor-803 elementor-8\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e6d86a elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"2e6d86a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e60e37b\" data-id=\"e60e37b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-106be45 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"106be45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;transition_speed&quot;:1000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInDown\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-0140514 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Port\u00e1l Invest Trade <\/div><div class=\"elementor-slide-description\">V\u00edtejte u profesion\u00e1l\u016f!\n<\/div><a href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/zaregistrujte-se\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">Zaregistrujte se<\/a><\/div><\/div><\/div><div class=\"elementor-repeater-item-bc4600c swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Port\u00e1l Invest Trade <\/div><div class=\"elementor-slide-description\">Obchodujte jako profesion\u00e1l\n<\/div><a href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/ucty\/\" class=\"elementor-button elementor-slide-button elementor-size-md\">\u00da\u010dty<\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd0650e elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd0650e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4424d14\" data-id=\"4424d14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19f2adc elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"19f2adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"104\" height=\"105\" viewBox=\"0 0 104 105\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.30675 0.00011279C4.1929 0.00191977 4.08053 0.0261366 3.97604 0.0713801C3.87155 0.116624 3.777 0.182007 3.69779 0.263797C3.61858 0.345587 3.55625 0.44218 3.51437 0.548061C3.47249 0.653941 3.45188 0.767034 3.45372 0.880881V98.8265H0.866898C0.636982 98.8265 0.416484 98.9178 0.253909 99.0804C0.0913338 99.2429 0 99.4634 0 99.6934C0 99.9233 0.0913338 100.144 0.253909 100.306C0.416484 100.469 0.636982 100.56 0.866898 100.56H3.45372V103.151C3.45372 103.38 3.54505 103.601 3.70763 103.764C3.8702 103.926 4.0907 104.017 4.32062 104.017C4.55053 104.017 4.77103 103.926 4.93361 103.764C5.09618 103.601 5.18752 103.38 5.18752 103.151V100.56H103.133C103.363 100.56 103.584 100.469 103.746 100.306C103.909 100.144 104 99.9233 104 99.6934C104 99.4634 103.909 99.2429 103.746 99.0804C103.584 98.9178 103.363 98.8265 103.133 98.8265H11.398L33.3253 71.4238L44.3002 78.7352C45.5802 79.5855 47.1347 79.9195 48.6509 79.6702C50.1672 79.421 51.5329 78.6068 52.4733 77.3915L66.2431 59.4901L73.6118 64.7574C74.8835 65.6622 76.4544 66.0434 77.9994 65.822C79.5444 65.6006 80.945 64.7936 81.9114 63.568L96.5707 44.9054L101.691 50.0271C101.812 50.1486 101.966 50.2314 102.135 50.265C102.303 50.2986 102.478 50.2814 102.636 50.2157C102.795 50.1499 102.93 50.0386 103.026 49.8957C103.121 49.7529 103.172 49.585 103.171 49.4133V30.3415C103.171 30.1116 103.08 29.8911 102.917 29.7285C102.755 29.566 102.534 29.4746 102.304 29.4746H97.0041L97.129 29.492C96.7422 29.4348 96.3508 29.4156 95.9604 29.4348V29.4278C95.7939 29.4278 95.6292 29.4504 95.4628 29.4712H83.2326C83.0609 29.4709 82.893 29.5215 82.7502 29.6168C82.6073 29.712 82.496 29.8475 82.4302 30.0061C82.3645 30.1647 82.3473 30.3393 82.3809 30.5076C82.4145 30.676 82.4973 30.8306 82.6188 30.9518L87.9242 36.2607L75.9507 51.5094L68.5317 46.2092C67.2515 45.2989 65.6688 44.9192 64.1149 45.1496C62.561 45.3801 61.1566 46.2028 60.1957 47.4454L46.3131 65.4908L35.4249 58.2314C34.1606 57.3929 32.6285 57.0573 31.1295 57.2905C29.6304 57.5237 28.2727 58.3089 27.3229 59.4918L5.18752 87.1667V0.880881C5.18939 0.764699 5.16789 0.649327 5.12429 0.541621C5.08069 0.433914 5.01588 0.336072 4.93372 0.253909C4.85156 0.171745 4.75372 0.106938 4.64601 0.0633392C4.5383 0.0197401 4.42293 -0.00176147 4.30675 0.00011279ZM96.0419 31.1564C96.321 31.1391 96.6019 31.1564 96.8793 31.198C96.9209 31.201 96.9626 31.201 97.0041 31.198H101.437V47.3102L97.1064 42.9792C97.0197 42.8927 96.9157 42.8257 96.8012 42.7823C96.6868 42.739 96.5644 42.7204 96.4422 42.7278C96.32 42.7352 96.2008 42.7683 96.0923 42.8251C95.9839 42.8819 95.8887 42.961 95.813 43.0572L80.5504 62.4844C79.8629 63.3641 78.8618 63.9438 77.7566 64.1022C76.6513 64.2605 75.5277 63.9852 74.6208 63.3339L66.5708 57.5847C66.3883 57.4539 66.1621 57.3991 65.9399 57.4317C65.7177 57.4644 65.5169 57.582 65.3797 57.7598L51.0984 76.3218C50.4298 77.194 49.4541 77.7789 48.3697 77.9573C47.2852 78.1357 46.1735 77.8944 45.2607 77.2823L33.627 69.5288C33.4464 69.4077 33.227 69.3589 33.0122 69.392C32.7974 69.425 32.6028 69.5376 32.4671 69.7074L9.17698 98.8178H5.18752V89.9304L28.6787 60.5685C29.3546 59.7198 30.325 59.1563 31.3971 58.9899C32.4693 58.8235 33.5648 59.0664 34.4661 59.6704L46.0271 67.3771C46.2095 67.4996 46.4317 67.5482 46.6486 67.5132C46.8656 67.4781 47.0611 67.3619 47.1957 67.1882L61.5688 48.503C62.2514 47.6103 63.2549 47.0187 64.3664 46.8536C65.478 46.6885 66.6101 46.963 67.5227 47.6188L75.616 53.3993C75.7976 53.529 76.0222 53.5838 76.2431 53.5521C76.464 53.5205 76.6641 53.4049 76.8019 53.2294L89.7638 36.7236C89.8952 36.557 89.9609 36.3479 89.9484 36.136C89.936 35.9242 89.8462 35.7242 89.6962 35.5741L85.3253 31.2015H95.4853C95.5263 31.2044 95.5674 31.2044 95.6084 31.2015C95.7521 31.1801 95.8968 31.1657 96.0419 31.1582V31.1564Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDostupn\u00e1 aktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t 300 + nejobl\u00edben\u011bj\u0161\u00ed aktiva\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c1b7bb5\" data-id=\"c1b7bb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36a3aec elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"36a3aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"104\" height=\"104\" viewBox=\"0 0 104 104\" fill=\"none\"><path d=\"M11.609 0C10.2561 0.00683288 8.96059 0.547295 8.00394 1.50394C7.0473 2.46059 6.50683 3.75612 6.5 5.109V45.5H0V104H104V45.5H86.255L87.75 45.4253L87.6688 43.8815L84.4252 44.0407L84.4935 45.5H81.211C81.211 38.805 78.6663 32.3473 74.0123 27.495C69.8837 23.2056 64.4078 20.4636 58.5 19.7275V16.445L59.6732 16.6205L60.1705 13.4095L58.6528 13.1755H58.5V5.1155C58.4949 3.76149 57.9552 2.4643 56.9983 1.50625C56.0415 0.548203 54.745 0.00684611 53.391 0L11.609 0ZM11.609 3.25H13V45.5H9.75V5.109C9.74468 4.86341 9.78913 4.61929 9.88067 4.39134C9.97221 4.16339 10.1089 3.95633 10.2826 3.78264C10.4563 3.60894 10.6634 3.47221 10.8913 3.38067C11.1193 3.28913 11.3634 3.24468 11.609 3.25ZM16.25 3.25H22.75V45.5H16.25V3.25ZM26 3.25H53.391C54.4472 3.25 55.25 4.05275 55.25 5.109V45.5H52V39H48.75V45.5H42.25V39H32.5V45.5H26V3.25ZM37.375 6.5C35.2222 6.50686 33.1596 7.36508 31.6373 8.88733C30.1151 10.4096 29.2569 12.4722 29.25 14.625C29.25 16.4515 29.8838 18.1187 30.914 19.4805C29.8512 20.878 29.25 22.5907 29.25 24.375C29.25 28.8438 32.9062 32.5 37.375 32.5C41.8438 32.5 45.5 28.8438 45.5 24.375C45.5 22.5907 44.8988 20.8813 43.836 19.4805C44.9071 18.0877 45.4916 16.382 45.5 14.625C45.5 10.1562 41.8438 6.5 37.375 6.5ZM37.375 9.75C40.0855 9.75 42.25 11.9145 42.25 14.625C42.25 15.9738 41.7137 17.186 40.8395 18.0667L40.7583 18.135C40.6933 18.2 40.6185 18.2487 40.5503 18.3072C40.1213 18.6745 39.6402 18.9702 39.1203 19.1685C39.0942 19.1815 39.065 19.1847 39.039 19.1945C38.5093 19.3895 37.947 19.5 37.375 19.5C36.803 19.5 36.2407 19.3895 35.711 19.1945C35.685 19.1847 35.6558 19.1815 35.6297 19.1685C35.1071 18.9659 34.6233 18.6745 34.1997 18.3072C34.1348 18.2487 34.0567 18.1968 33.9917 18.135L33.9105 18.0667C33.4609 17.6138 33.1049 17.0767 32.8629 16.4862C32.6208 15.8956 32.4975 15.2632 32.5 14.625C32.5 11.9145 34.6645 9.75 37.375 9.75ZM63.5083 14.066L62.6958 17.2478L63.869 17.5435H63.9015L65.6338 18.174L66.7517 15.119L64.987 14.4788L64.9122 14.4463L64.8343 14.4105L63.5083 14.066ZM69.8685 16.51L68.458 19.4318L69.2217 19.799L69.2607 19.8315L71.1393 20.9788L72.8293 18.2065L70.8078 16.9812L70.7428 16.9293L70.6777 16.8967L69.8685 16.51ZM75.595 20.1663L73.645 22.776L73.7978 22.8768L73.8302 22.9158L75.9492 24.8398L78.1397 22.4347L75.9818 20.4783L75.9232 20.4132L75.8582 20.371L75.595 20.1663ZM33.5985 21.7652C34.736 22.3698 36.0035 22.75 37.375 22.75C38.6959 22.7388 39.9933 22.4004 41.1515 21.7652C41.743 22.5452 42.25 23.387 42.25 24.375C42.25 27.0855 40.0855 29.25 37.375 29.25C34.6645 29.25 32.5 27.0855 32.5 24.375C32.5 23.387 33.007 22.542 33.5985 21.7652ZM58.5 23.01C63.5162 23.7267 68.1491 26.0992 71.6625 29.7505C75.7212 33.9886 77.9839 39.6319 77.9772 45.5H73.125L74.75 45.4188L74.6915 44.2812L71.4415 44.4535L71.4935 45.5H58.5V29.588H58.5195L58.994 29.7083L59.8 26.5557L59.254 26.4192L59.1792 26.3802H59.098L58.5 26.2925V23.01ZM80.5187 25.0737L77.9188 27.0237L79.5177 29.1622L79.7323 29.523L82.5143 27.833L82.2412 27.391L82.2022 27.326L82.1503 27.261L80.5187 25.0737ZM48.75 26V35.75H52V26H48.75ZM63.18 27.6997L61.7695 30.6248L62.9947 31.2162L64.3078 32.0125L64.3403 32.045H64.3467L64.402 32.0807L64.766 31.4827L66.287 29.4482L66.2188 29.3898L66.1537 29.3378L66.0855 29.302L64.6133 28.405L64.5482 28.3628L64.4735 28.3302L63.1767 27.6997H63.18ZM84.2075 30.7872L81.276 32.1945L82.1958 34.099L82.5338 35.0187L85.5855 33.904L85.2247 32.9193L85.1988 32.8412L85.1597 32.773L84.2075 30.7872ZM68.9097 31.5802L67.1385 33.54L66.69 33.9527L66.7258 33.9983L66.7517 34.0308L66.7972 34.073L67.7398 35.113H67.756L68.6042 36.2505L71.2075 34.3005L70.3463 33.1533L70.3008 33.0882L70.2423 33.033L69.095 31.7655L69.0365 31.7005L68.9813 31.6485L68.9097 31.5802ZM86.6255 37.154L83.4795 37.9535L83.902 39.611L84.1133 40.976L87.3242 40.4787L87.1032 39.0325L87.0903 38.948L87.0708 38.8733L86.6255 37.1507V37.154ZM72.9755 37.3945L70.0472 38.8083L70.2098 39.1592L70.7558 40.6445L70.9995 41.5708L74.1455 40.7648L73.892 39.78L73.8725 39.6987L73.8497 39.6273L73.2453 37.9795L73.2192 37.908L73.1835 37.8332L72.9722 37.3945H72.9755ZM35.75 42.25H39V45.5H35.75V42.25ZM3.25 48.75H100.75V100.75H3.25V48.75ZM16.25 52V53.625C16.25 58.1328 12.6327 61.75 8.125 61.75H6.5V87.75H8.125C12.6327 87.75 16.25 91.3672 16.25 95.875V97.5H87.75V95.875C87.75 91.3672 91.3672 87.75 95.875 87.75H97.5V61.75H95.875C94.807 61.7534 93.749 61.5456 92.7616 61.1385C91.7743 60.7314 90.8773 60.1331 90.1221 59.3779C89.3669 58.6227 88.7686 57.7257 88.3615 56.7384C87.9544 55.751 87.7466 54.693 87.75 53.625V52H16.25ZM19.1685 55.25H84.8315C85.176 57.6256 86.2792 59.8261 87.9765 61.5235C89.6739 63.2208 91.8744 64.324 94.25 64.6685V84.8315C91.8746 85.1765 89.6744 86.2799 87.9771 87.9771C86.2799 89.6744 85.1765 91.8746 84.8315 94.25H19.1685C18.8235 91.8746 17.7201 89.6744 16.0229 87.9771C14.3256 86.2799 12.1254 85.1765 9.75 84.8315V64.6685C12.1256 64.324 14.3261 63.2208 16.0235 61.5235C17.7208 59.8261 18.824 57.6256 19.1685 55.25ZM43.966 61.75V61.7825H43.888V65.0325H47.2257C50.258 65.0325 51.792 66.4658 52.3412 68.25H43.9628V71.5H52.3412C51.792 73.2842 50.2612 74.724 47.2257 74.724H43.8848V77.974H44.8467L54.7593 87.75L57.0472 85.4425L49.2635 77.7595C52.7897 77.0185 55.0518 74.3958 55.6758 71.5H60.112V68.25H55.6758C55.4223 67.08 54.8762 65.975 54.1157 65H60.112V61.75H43.966ZM19.5 71.5C17.7255 71.5 16.25 72.9755 16.25 74.75C16.25 76.5245 17.7255 78 19.5 78C21.2745 78 22.75 76.5245 22.75 74.75C22.75 72.9755 21.2745 71.5 19.5 71.5ZM84.5 71.5C82.7255 71.5 81.25 72.9755 81.25 74.75C81.25 76.5245 82.7255 78 84.5 78C86.2745 78 87.75 76.5245 87.75 74.75C87.75 72.9755 86.2745 71.5 84.5 71.5Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed velikost obchodu\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKa\u017ed\u00fd si m\u016f\u017ee dovolit investovat\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8bbc1b0\" data-id=\"8bbc1b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43b7eb2 elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"43b7eb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"91\" height=\"105\" viewBox=\"0 0 91 105\" fill=\"none\"><path d=\"M73.0707 74.4203H67.556C67.1904 74.4203 66.8397 74.5315 66.5812 74.7295C66.3226 74.9275 66.1774 75.196 66.1774 75.476C66.1774 75.756 66.3226 76.0245 66.5812 76.2225C66.8397 76.4204 67.1904 76.5316 67.556 76.5316H70.3134V78.643C70.3134 78.923 70.4586 79.1915 70.7172 79.3895C70.9757 79.5875 71.3264 79.6987 71.6921 79.6987C72.0577 79.6987 72.4084 79.5875 72.6669 79.3895C72.9255 79.1915 73.0707 78.923 73.0707 78.643V76.5316C74.1677 76.5316 75.2197 76.198 75.9953 75.604C76.771 75.0101 77.2068 74.2046 77.2068 73.3646V71.2533C77.2068 70.4133 76.771 69.6078 75.9953 69.0139C75.2197 68.4199 74.1677 68.0863 73.0707 68.0863H70.3134C69.9477 68.0863 69.5971 67.975 69.3385 67.7771C69.08 67.5791 68.9347 67.3106 68.9347 67.0306V64.9192C68.9347 64.6393 69.08 64.3707 69.3385 64.1728C69.5971 63.9748 69.9477 63.8636 70.3134 63.8636H75.8281C76.1937 63.8636 76.5444 63.7523 76.803 63.5544C77.0615 63.3564 77.2068 63.0879 77.2068 62.8079C77.2068 62.5279 77.0615 62.2594 76.803 62.0614C76.5444 61.8634 76.1937 61.7522 75.8281 61.7522H73.0707V59.6409C73.0707 59.3609 72.9255 59.0924 72.6669 58.8944C72.4084 58.6964 72.0577 58.5852 71.6921 58.5852C71.3264 58.5852 70.9757 58.6964 70.7172 58.8944C70.4586 59.0924 70.3134 59.3609 70.3134 59.6409V61.7522C69.2165 61.7522 68.1644 62.0859 67.3888 62.6798C66.6131 63.2737 66.1774 64.0793 66.1774 64.9192V67.0306C66.1774 67.8705 66.6131 68.6761 67.3888 69.27C68.1644 69.8639 69.2165 70.1976 70.3134 70.1976H73.0707C73.4364 70.1976 73.7871 70.3088 74.0456 70.5068C74.3042 70.7048 74.4494 70.9733 74.4494 71.2533V73.3646C74.4494 73.6446 74.3042 73.9131 74.0456 74.1111C73.7871 74.3091 73.4364 74.4203 73.0707 74.4203ZM86.1957 90.4665L57.9053 92.276V89.6896C57.9154 88.0981 57.2499 86.5472 56.0091 85.2704C54.7684 83.9936 53.0195 83.06 51.0258 82.6102L30.172 77.8217C29.9368 77.151 29.4202 76.558 28.7017 76.1342C27.9833 75.7103 27.1028 75.4791 26.1959 75.476H4.1371C3.77145 75.476 3.42078 75.5872 3.16223 75.7852C2.90368 75.9832 2.75842 76.2517 2.75842 76.5316L2.75842 99.7565C2.75842 100.036 2.90368 100.305 3.16223 100.503C3.42078 100.701 3.77145 100.812 4.1371 100.812H26.1959C26.9835 100.81 27.754 100.636 28.4169 100.31C29.0797 99.9846 29.6073 99.5207 29.9376 98.9732L51.9495 104.03C54.9408 104.721 58.1384 104.684 61.1011 103.924L87.9604 97.0687C88.9907 96.8078 89.8601 96.2664 90.4038 95.5473C90.9475 94.8281 91.1276 93.9812 90.91 93.1671C90.6924 92.353 90.0922 91.6284 89.2233 91.1306C88.3543 90.6328 87.277 90.3966 86.1957 90.4665ZM19.3025 98.7008H5.51577V77.5873H19.3025V98.7008ZM27.5745 97.6451C27.5745 97.9251 27.4293 98.1936 27.1707 98.3916C26.9122 98.5896 26.5615 98.7008 26.1959 98.7008H22.0598V77.5873H26.1959C26.5615 77.5873 26.9122 77.6985 27.1707 77.8965C27.4293 78.0945 27.5745 78.363 27.5745 78.643V97.6451ZM87.0918 95.063L60.2298 101.919C57.8057 102.541 55.1889 102.572 52.7408 102.007L30.3319 96.8597V80.0618L50.2344 84.6329C51.6578 84.9551 52.9062 85.6221 53.7922 86.5339C54.6782 87.4458 55.154 88.5531 55.148 89.6896V91.8621L43.2528 88.218C43.0835 88.1609 42.9008 88.1305 42.7158 88.1286C42.5308 88.1267 42.3472 88.1534 42.1759 88.207C42.0046 88.2606 41.8492 88.34 41.7189 88.4406C41.5885 88.5411 41.486 88.6608 41.4173 88.7923C41.3486 88.9239 41.3152 89.0647 41.3191 89.2063C41.3229 89.348 41.364 89.4876 41.4398 89.6168C41.5157 89.746 41.6247 89.8623 41.7604 89.9586C41.8961 90.0549 42.0558 90.1292 42.2298 90.1773L56.0166 94.4H56.0524C56.1193 94.4138 56.1876 94.4236 56.2564 94.4295C56.3464 94.4499 56.4387 94.4634 56.5322 94.4697C56.5487 94.4697 56.5625 94.4697 56.5791 94.4591C56.5956 94.4486 56.6232 94.4591 56.648 94.4591L86.4273 92.5589C86.8368 92.5302 87.2457 92.618 87.5758 92.8057C87.9059 92.9933 88.1341 93.2676 88.2167 93.576C88.2993 93.8844 88.2306 94.2053 88.0235 94.4773C87.8165 94.7493 87.4858 94.9533 87.0946 95.0503L87.0918 95.063ZM71.6921 83.9214C75.5095 83.9214 79.2413 83.0546 82.4154 81.4306C85.5895 79.8066 88.0634 77.4984 89.5243 74.7978C90.9851 72.0972 91.3674 69.1255 90.6226 66.2586C89.8779 63.3917 88.0396 60.7582 85.3402 58.6913C82.6409 56.6244 79.2017 55.2167 75.4576 54.6465C71.7135 54.0762 67.8326 54.3689 64.3057 55.4875C60.7789 56.6061 57.7644 58.5005 55.6435 60.9309C53.5227 63.3614 52.3906 66.2188 52.3906 69.1419C52.3965 73.0603 54.4319 76.8169 58.0504 79.5876C61.6688 82.3583 66.5748 83.9169 71.6921 83.9214ZM71.6921 56.4738C74.9642 56.4738 78.1628 57.2168 80.8835 58.6088C83.6041 60.0008 85.7246 61.9793 86.9768 64.2941C88.229 66.6089 88.5566 69.156 87.9183 71.6134C87.2799 74.0707 85.7042 76.328 83.3905 78.0996C81.0768 79.8713 78.1289 81.0778 74.9197 81.5666C71.7104 82.0554 68.384 81.8045 65.3609 80.8457C62.3379 79.8869 59.7541 78.2632 57.9362 76.1799C56.1183 74.0967 55.148 71.6474 55.148 69.1419C55.1531 65.7833 56.8978 62.5634 59.9993 60.1886C63.1008 57.8137 67.3059 56.4778 71.6921 56.4738Z\" fill=\"white\"><\/path><path d=\"M17.9291 20.0578H23.4438C23.8095 20.0578 24.1601 20.169 24.4187 20.367C24.6773 20.565 24.8225 20.8335 24.8225 21.1135C24.8225 21.3935 24.6773 21.662 24.4187 21.86C24.1601 22.0579 23.8095 22.1692 23.4438 22.1692H20.6865V24.2805C20.6865 24.5605 20.5412 24.829 20.2827 25.027C20.0241 25.225 19.6735 25.3362 19.3078 25.3362C18.9422 25.3362 18.5915 25.225 18.3329 25.027C18.0744 24.829 17.9291 24.5605 17.9291 24.2805V22.1692C16.8322 22.1692 15.7802 21.8355 15.0045 21.2416C14.2289 20.6476 13.7931 19.8421 13.7931 19.0021V16.8908C13.7931 16.0508 14.2289 15.2453 15.0045 14.6514C15.7802 14.0574 16.8322 13.7238 17.9291 13.7238H20.6865C21.0521 13.7238 21.4028 13.6125 21.6614 13.4146C21.9199 13.2166 22.0652 12.9481 22.0652 12.6681V10.5567C22.0652 10.2768 21.9199 10.0083 21.6614 9.81027C21.4028 9.6123 21.0521 9.50107 20.6865 9.50107H15.1718C14.8061 9.50107 14.4555 9.38985 14.1969 9.19187C13.9384 8.9939 13.7931 8.72538 13.7931 8.4454C13.7931 8.16542 13.9384 7.8969 14.1969 7.69892C14.4555 7.50095 14.8061 7.38973 15.1718 7.38973H17.9291V5.27838C17.9291 4.9984 18.0744 4.72988 18.3329 4.5319C18.5915 4.33393 18.9422 4.2227 19.3078 4.2227C19.6735 4.2227 20.0241 4.33393 20.2827 4.5319C20.5412 4.72988 20.6865 4.9984 20.6865 5.27838V7.38973C21.7834 7.38973 22.8354 7.72339 23.6111 8.31732C24.3867 8.91126 24.8225 9.7168 24.8225 10.5567V12.6681C24.8225 13.508 24.3867 14.3136 23.6111 14.9075C22.8354 15.5015 21.7834 15.8351 20.6865 15.8351H17.9291C17.5635 15.8351 17.2128 15.9463 16.9543 16.1443C16.6957 16.3423 16.5505 16.6108 16.5505 16.8908V19.0021C16.5505 19.2821 16.6957 19.5506 16.9543 19.7486C17.2128 19.9466 17.5635 20.0578 17.9291 20.0578ZM4.80418 36.1041L33.0945 37.9135V35.3271C33.0845 33.7356 33.75 32.1847 34.9907 30.9079C36.2315 29.6311 37.9804 28.6975 39.9741 28.2477L60.8279 23.4592C61.0631 22.7885 61.5797 22.1956 62.2982 21.7717C63.0166 21.3479 63.8971 21.1166 64.804 21.1135H86.8628C87.2284 21.1135 87.5791 21.2247 87.8377 21.4227C88.0962 21.6207 88.2415 21.8892 88.2415 22.1692V45.394C88.2415 45.674 88.0962 45.9425 87.8377 46.1405C87.5791 46.3384 87.2284 46.4497 86.8628 46.4497H64.804C64.0164 46.4478 63.2458 46.2737 62.583 45.9479C61.9202 45.6221 61.3926 45.1582 61.0623 44.6107L39.0504 49.6674C36.0591 50.3583 32.8615 50.3214 29.8988 49.5618L3.03947 42.7062C2.00916 42.4453 1.13973 41.9039 0.596054 41.1848C0.0523758 40.4656 -0.127747 39.6187 0.0898514 38.8046C0.307449 37.9905 0.907631 37.2659 1.77658 36.7681C2.64553 36.2704 3.72283 36.0341 4.80418 36.1041ZM71.6974 44.3383H85.4841V23.2248H71.6974V44.3383ZM63.4253 43.2826C63.4253 43.5626 63.5706 43.8311 63.8291 44.0291C64.0877 44.2271 64.4384 44.3383 64.804 44.3383H68.94V23.2248H64.804C64.4384 23.2248 64.0877 23.3361 63.8291 23.534C63.5706 23.732 63.4253 24.0005 63.4253 24.2805V43.2826ZM3.90804 40.7005L30.7701 47.556C33.1942 48.1787 35.811 48.2097 38.259 47.6447L60.668 42.4972V25.6993L40.7655 30.2704C39.3421 30.5926 38.0937 31.2596 37.2077 32.1715C36.3217 33.0833 35.8459 34.1906 35.8519 35.3271V37.4997L47.7471 33.8555C47.9164 33.7984 48.099 33.768 48.2841 33.7661C48.4691 33.7642 48.6527 33.7909 48.824 33.8445C48.9952 33.8981 49.1507 33.9775 49.281 34.0781C49.4114 34.1786 49.5139 34.2983 49.5826 34.4298C49.6513 34.5614 49.6847 34.7022 49.6808 34.8438C49.6769 34.9855 49.6359 35.1251 49.56 35.2543C49.4842 35.3835 49.3752 35.4998 49.2395 35.5961C49.1038 35.6924 48.9441 35.7668 48.7701 35.8148L34.9833 40.0375H34.9475C34.8805 40.0513 34.8123 40.0611 34.7434 40.0671C34.6535 40.0875 34.5611 40.1009 34.4677 40.1072C34.4512 40.1072 34.4374 40.1072 34.4208 40.0966C34.4043 40.0861 34.3767 40.0966 34.3519 40.0966L4.57256 38.1964C4.16312 38.1677 3.75422 38.2555 3.42408 38.4432C3.09393 38.6308 2.86574 38.9051 2.78313 39.2135C2.70053 39.5219 2.76933 39.8428 2.97636 40.1148C3.18339 40.3868 3.51412 40.5908 3.90528 40.6878L3.90804 40.7005ZM19.3078 29.5589C15.4904 29.5589 11.7586 28.6921 8.58452 27.0681C5.41042 25.4441 2.9365 23.1359 1.47562 20.4353C0.0147476 17.7347 -0.367485 14.763 0.377266 11.8961C1.12201 9.02919 2.9603 6.39575 5.65965 4.3288C8.359 2.26186 11.7982 0.854257 15.5423 0.283989C19.2864 -0.286278 23.1673 0.00640368 26.6941 1.12502C30.221 2.24364 33.2355 4.13796 35.3564 6.56843C37.4772 8.9989 38.6092 11.8563 38.6092 14.7794C38.6034 18.6978 36.568 22.4544 32.9495 25.2251C29.3311 27.9959 24.4251 29.5544 19.3078 29.5589ZM19.3078 2.11136C16.0357 2.11136 12.8371 2.85433 10.1164 4.24631C7.39576 5.6383 5.27526 7.61679 4.02308 9.93158C2.7709 12.2464 2.44327 14.7935 3.08163 17.2509C3.71999 19.7082 5.29565 21.9655 7.60938 23.7371C9.92311 25.5088 12.871 26.7153 16.0802 27.2041C19.2895 27.6929 22.6159 27.442 25.639 26.4832C28.662 25.5244 31.2458 23.9007 33.0637 21.8175C34.8816 19.7342 35.8519 17.285 35.8519 14.7794C35.8468 11.4209 34.1021 8.20095 31.0006 5.82607C27.8991 3.45119 23.694 2.11527 19.3078 2.11136Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed vklad\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBez provize\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d112440 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d112440\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6526089\" data-id=\"6526089\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d2967f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2967f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-24f175e\" data-id=\"24f175e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19e353d elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"19e353d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"104\" height=\"105\" viewBox=\"0 0 104 105\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.30675 0.00011279C4.1929 0.00191977 4.08053 0.0261366 3.97604 0.0713801C3.87155 0.116624 3.777 0.182007 3.69779 0.263797C3.61858 0.345587 3.55625 0.44218 3.51437 0.548061C3.47249 0.653941 3.45188 0.767034 3.45372 0.880881V98.8265H0.866898C0.636982 98.8265 0.416484 98.9178 0.253909 99.0804C0.0913338 99.2429 0 99.4634 0 99.6934C0 99.9233 0.0913338 100.144 0.253909 100.306C0.416484 100.469 0.636982 100.56 0.866898 100.56H3.45372V103.151C3.45372 103.38 3.54505 103.601 3.70763 103.764C3.8702 103.926 4.0907 104.017 4.32062 104.017C4.55053 104.017 4.77103 103.926 4.93361 103.764C5.09618 103.601 5.18752 103.38 5.18752 103.151V100.56H103.133C103.363 100.56 103.584 100.469 103.746 100.306C103.909 100.144 104 99.9233 104 99.6934C104 99.4634 103.909 99.2429 103.746 99.0804C103.584 98.9178 103.363 98.8265 103.133 98.8265H11.398L33.3253 71.4238L44.3002 78.7352C45.5802 79.5855 47.1347 79.9195 48.6509 79.6703C50.1672 79.421 51.5329 78.6068 52.4733 77.3915L66.2431 59.4901L73.6118 64.7574C74.8835 65.6622 76.4544 66.0434 77.9994 65.822C79.5444 65.6006 80.945 64.7936 81.9114 63.568L96.5707 44.9054L101.691 50.027C101.812 50.1486 101.966 50.2314 102.135 50.265C102.303 50.2986 102.478 50.2814 102.636 50.2157C102.795 50.1499 102.93 50.0386 103.026 49.8957C103.121 49.7529 103.172 49.585 103.171 49.4133V30.3415C103.171 30.1116 103.08 29.8911 102.917 29.7285C102.755 29.566 102.534 29.4746 102.304 29.4746H97.0041L97.129 29.492C96.7422 29.4348 96.3508 29.4156 95.9604 29.4348V29.4278C95.7939 29.4278 95.6292 29.4504 95.4628 29.4712H83.2326C83.0609 29.4709 82.893 29.5215 82.7502 29.6168C82.6073 29.712 82.496 29.8475 82.4302 30.0061C82.3645 30.1647 82.3473 30.3392 82.3809 30.5076C82.4145 30.676 82.4973 30.8306 82.6188 30.9518L87.9242 36.2607L75.9507 51.5094L68.5317 46.2092C67.2515 45.2989 65.6688 44.9192 64.1149 45.1496C62.561 45.3801 61.1566 46.2028 60.1957 47.4454L46.3131 65.4908L35.4249 58.2314C34.1606 57.3929 32.6285 57.0573 31.1295 57.2905C29.6304 57.5237 28.2727 58.3089 27.3229 59.4918L5.18752 87.1667V0.880881C5.18939 0.764699 5.16789 0.649327 5.12429 0.541621C5.08069 0.433914 5.01588 0.336072 4.93372 0.253909C4.85156 0.171745 4.75372 0.106938 4.64601 0.0633392C4.5383 0.0197401 4.42293 -0.00176147 4.30675 0.00011279ZM96.0419 31.1564C96.321 31.1391 96.6019 31.1564 96.8793 31.198C96.9209 31.201 96.9626 31.201 97.0041 31.198H101.437V47.3102L97.1064 42.9792C97.0197 42.8927 96.9157 42.8257 96.8012 42.7823C96.6868 42.739 96.5644 42.7204 96.4422 42.7278C96.32 42.7352 96.2008 42.7683 96.0923 42.8251C95.9839 42.8819 95.8887 42.961 95.813 43.0572L80.5504 62.4844C79.8629 63.3641 78.8618 63.9438 77.7566 64.1022C76.6513 64.2605 75.5277 63.9852 74.6208 63.3339L66.5708 57.5847C66.3883 57.4539 66.1621 57.3991 65.9399 57.4317C65.7177 57.4644 65.5169 57.582 65.3797 57.7598L51.0984 76.3218C50.4298 77.194 49.4541 77.7789 48.3697 77.9573C47.2852 78.1357 46.1735 77.8944 45.2607 77.2823L33.627 69.5288C33.4464 69.4077 33.227 69.3589 33.0122 69.392C32.7974 69.425 32.6028 69.5376 32.4671 69.7074L9.17698 98.8178H5.18752V89.9304L28.6787 60.5685C29.3546 59.7198 30.325 59.1563 31.3971 58.9899C32.4693 58.8235 33.5648 59.0664 34.4661 59.6704L46.0271 67.3771C46.2095 67.4996 46.4317 67.5482 46.6486 67.5132C46.8656 67.4781 47.0611 67.3619 47.1957 67.1882L61.5688 48.503C62.2514 47.6103 63.2549 47.0187 64.3664 46.8536C65.478 46.6885 66.6101 46.963 67.5227 47.6188L75.616 53.3993C75.7976 53.529 76.0222 53.5838 76.2431 53.5521C76.464 53.5205 76.6641 53.4049 76.8019 53.2294L89.7638 36.7236C89.8952 36.557 89.9609 36.3479 89.9484 36.136C89.936 35.9242 89.8462 35.7242 89.6962 35.5741L85.3253 31.2015H95.4853C95.5263 31.2044 95.5674 31.2044 95.6084 31.2015C95.7521 31.1801 95.8968 31.1657 96.0419 31.1582V31.1564Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Dostupn\u00e1 aktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t300 + nejobl\u00edben\u011bj\u0161\u00ed aktiva\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-156b8a5\" data-id=\"156b8a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df1b8da elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"df1b8da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"104\" height=\"104\" viewBox=\"0 0 104 104\" fill=\"none\"><path d=\"M11.609 0C10.2561 0.00683288 8.96059 0.547295 8.00394 1.50394C7.0473 2.46059 6.50683 3.75612 6.5 5.109V45.5H0V104H104V45.5H86.255L87.75 45.4253L87.6688 43.8815L84.4252 44.0407L84.4935 45.5H81.211C81.211 38.805 78.6663 32.3473 74.0123 27.495C69.8837 23.2056 64.4078 20.4636 58.5 19.7275V16.445L59.6733 16.6205L60.1705 13.4095L58.6528 13.1755H58.5V5.1155C58.4949 3.76149 57.9552 2.4643 56.9983 1.50625C56.0415 0.548203 54.745 0.00684611 53.391 0L11.609 0ZM11.609 3.25H13V45.5H9.75V5.109C9.74468 4.86341 9.78913 4.61929 9.88067 4.39134C9.97221 4.16339 10.1089 3.95633 10.2826 3.78264C10.4563 3.60894 10.6634 3.47221 10.8913 3.38067C11.1193 3.28913 11.3634 3.24468 11.609 3.25ZM16.25 3.25H22.75V45.5H16.25V3.25ZM26 3.25H53.391C54.4472 3.25 55.25 4.05275 55.25 5.109V45.5H52V39H48.75V45.5H42.25V39H32.5V45.5H26V3.25ZM37.375 6.5C35.2222 6.50686 33.1596 7.36508 31.6373 8.88733C30.1151 10.4096 29.2569 12.4722 29.25 14.625C29.25 16.4515 29.8838 18.1187 30.914 19.4805C29.8513 20.878 29.25 22.5907 29.25 24.375C29.25 28.8438 32.9062 32.5 37.375 32.5C41.8438 32.5 45.5 28.8438 45.5 24.375C45.5 22.5907 44.8987 20.8812 43.836 19.4805C44.9071 18.0877 45.4917 16.382 45.5 14.625C45.5 10.1562 41.8438 6.5 37.375 6.5ZM37.375 9.75C40.0855 9.75 42.25 11.9145 42.25 14.625C42.25 15.9737 41.7137 17.186 40.8395 18.0668L40.7583 18.135C40.6933 18.2 40.6185 18.2487 40.5503 18.3072C40.1213 18.6745 39.6402 18.9702 39.1202 19.1685C39.0942 19.1815 39.065 19.1848 39.039 19.1945C38.5093 19.3895 37.947 19.5 37.375 19.5C36.803 19.5 36.2407 19.3895 35.711 19.1945C35.685 19.1848 35.6558 19.1815 35.6298 19.1685C35.1071 18.9659 34.6233 18.6745 34.1997 18.3072C34.1347 18.2487 34.0567 18.1967 33.9917 18.135L33.9105 18.0668C33.4609 17.6138 33.1049 17.0767 32.8629 16.4862C32.6208 15.8956 32.4975 15.2632 32.5 14.625C32.5 11.9145 34.6645 9.75 37.375 9.75ZM63.5083 14.066L62.6958 17.2478L63.869 17.5435H63.9015L65.6337 18.174L66.7517 15.119L64.987 14.4787L64.9122 14.4463L64.8342 14.4105L63.5083 14.066ZM69.8685 16.51L68.458 19.4318L69.2217 19.799L69.2608 19.8315L71.1392 20.9787L72.8293 18.2065L70.8078 16.9812L70.7428 16.9293L70.6777 16.8967L69.8685 16.51ZM75.595 20.1662L73.645 22.776L73.7978 22.8768L73.8302 22.9158L75.9492 24.8398L78.1397 22.4347L75.9817 20.4783L75.9233 20.4133L75.8582 20.371L75.595 20.1662ZM33.5985 21.7653C34.736 22.3698 36.0035 22.75 37.375 22.75C38.6959 22.7388 39.9933 22.4004 41.1515 21.7653C41.743 22.5453 42.25 23.387 42.25 24.375C42.25 27.0855 40.0855 29.25 37.375 29.25C34.6645 29.25 32.5 27.0855 32.5 24.375C32.5 23.387 33.007 22.542 33.5985 21.7653ZM58.5 23.01C63.5162 23.7267 68.1491 26.0992 71.6625 29.7505C75.7212 33.9886 77.9839 39.6319 77.9773 45.5H73.125L74.75 45.4188L74.6915 44.2812L71.4415 44.4535L71.4935 45.5H58.5V29.588H58.5195L58.994 29.7082L59.8 26.5557L59.254 26.4192L59.1792 26.3802H59.098L58.5 26.2925V23.01ZM80.5187 25.0738L77.9188 27.0237L79.5177 29.1622L79.7323 29.523L82.5142 27.833L82.2413 27.391L82.2022 27.326L82.1503 27.261L80.5187 25.0738ZM48.75 26V35.75H52V26H48.75ZM63.18 27.6997L61.7695 30.6248L62.9947 31.2162L64.3078 32.0125L64.3403 32.045H64.3467L64.402 32.0808L64.766 31.4828L66.287 29.4482L66.2188 29.3898L66.1537 29.3378L66.0855 29.302L64.6133 28.405L64.5483 28.3628L64.4735 28.3303L63.1767 27.6997H63.18ZM84.2075 30.7872L81.276 32.1945L82.1958 34.099L82.5338 35.0187L85.5855 33.904L85.2247 32.9192L85.1988 32.8412L85.1597 32.773L84.2075 30.7872ZM68.9097 31.5803L67.1385 33.54L66.69 33.9527L66.7258 33.9983L66.7517 34.0307L66.7972 34.073L67.7398 35.113H67.756L68.6042 36.2505L71.2075 34.3005L70.3463 33.1533L70.3008 33.0882L70.2423 33.033L69.095 31.7655L69.0365 31.7005L68.9813 31.6485L68.9097 31.5803ZM86.6255 37.154L83.4795 37.9535L83.902 39.611L84.1133 40.976L87.3242 40.4787L87.1033 39.0325L87.0903 38.948L87.0708 38.8733L86.6255 37.1507V37.154ZM72.9755 37.3945L70.0472 38.8082L70.2098 39.1592L70.7557 40.6445L70.9995 41.5708L74.1455 40.7648L73.892 39.78L73.8725 39.6988L73.8497 39.6272L73.2453 37.9795L73.2192 37.908L73.1835 37.8332L72.9722 37.3945H72.9755ZM35.75 42.25H39V45.5H35.75V42.25ZM3.25 48.75H100.75V100.75H3.25V48.75ZM16.25 52V53.625C16.25 58.1327 12.6327 61.75 8.125 61.75H6.5V87.75H8.125C12.6327 87.75 16.25 91.3673 16.25 95.875V97.5H87.75V95.875C87.75 91.3673 91.3673 87.75 95.875 87.75H97.5V61.75H95.875C94.807 61.7534 93.749 61.5456 92.7616 61.1385C91.7743 60.7314 90.8773 60.1331 90.1221 59.3779C89.3669 58.6227 88.7686 57.7257 88.3615 56.7384C87.9544 55.751 87.7466 54.693 87.75 53.625V52H16.25ZM19.1685 55.25H84.8315C85.176 57.6256 86.2792 59.8261 87.9765 61.5235C89.6739 63.2208 91.8744 64.324 94.25 64.6685V84.8315C91.8746 85.1765 89.6744 86.2799 87.9771 87.9771C86.2799 89.6744 85.1765 91.8746 84.8315 94.25H19.1685C18.8235 91.8746 17.7201 89.6744 16.0229 87.9771C14.3256 86.2799 12.1254 85.1765 9.75 84.8315V64.6685C12.1256 64.324 14.3261 63.2208 16.0235 61.5235C17.7208 59.8261 18.824 57.6256 19.1685 55.25ZM43.966 61.75V61.7825H43.888V65.0325H47.2258C50.258 65.0325 51.792 66.4657 52.3412 68.25H43.9628V71.5H52.3412C51.792 73.2843 50.2613 74.724 47.2258 74.724H43.8848V77.974H44.8467L54.7593 87.75L57.0472 85.4425L49.2635 77.7595C52.7898 77.0185 55.0518 74.3957 55.6758 71.5H60.112V68.25H55.6758C55.4223 67.08 54.8762 65.975 54.1157 65H60.112V61.75H43.966ZM19.5 71.5C17.7255 71.5 16.25 72.9755 16.25 74.75C16.25 76.5245 17.7255 78 19.5 78C21.2745 78 22.75 76.5245 22.75 74.75C22.75 72.9755 21.2745 71.5 19.5 71.5ZM84.5 71.5C82.7255 71.5 81.25 72.9755 81.25 74.75C81.25 76.5245 82.7255 78 84.5 78C86.2745 78 87.75 76.5245 87.75 74.75C87.75 72.9755 86.2745 71.5 84.5 71.5Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed velikost obchodu\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKa\u017ed\u00fd si m\u016f\u017ee dovolit investovat\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2f7c4dc\" data-id=\"2f7c4dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c09d9f elementor-position-inline-start elementor-mobile-position-inline-start elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"0c09d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"91\" height=\"105\" viewBox=\"0 0 91 105\" fill=\"none\"><path d=\"M73.0707 74.4202H67.556C67.1904 74.4202 66.8397 74.5315 66.5812 74.7294C66.3226 74.9274 66.1774 75.1959 66.1774 75.4759C66.1774 75.7559 66.3226 76.0244 66.5812 76.2224C66.8397 76.4204 67.1904 76.5316 67.556 76.5316H70.3134V78.6429C70.3134 78.9229 70.4586 79.1914 70.7172 79.3894C70.9757 79.5874 71.3264 79.6986 71.6921 79.6986C72.0577 79.6986 72.4084 79.5874 72.6669 79.3894C72.9255 79.1914 73.0707 78.9229 73.0707 78.6429V76.5316C74.1677 76.5316 75.2197 76.1979 75.9953 75.604C76.771 75.0101 77.2068 74.2045 77.2068 73.3646V71.2532C77.2068 70.4133 76.771 69.6077 75.9953 69.0138C75.2197 68.4199 74.1677 68.0862 73.0707 68.0862H70.3134C69.9477 68.0862 69.5971 67.975 69.3385 67.777C69.08 67.579 68.9347 67.3105 68.9347 67.0305V64.9192C68.9347 64.6392 69.08 64.3707 69.3385 64.1727C69.5971 63.9747 69.9477 63.8635 70.3134 63.8635H75.8281C76.1937 63.8635 76.5444 63.7523 76.803 63.5543C77.0615 63.3563 77.2068 63.0878 77.2068 62.8078C77.2068 62.5278 77.0615 62.2593 76.803 62.0614C76.5444 61.8634 76.1937 61.7522 75.8281 61.7522H73.0707V59.6408C73.0707 59.3608 72.9255 59.0923 72.6669 58.8943C72.4084 58.6964 72.0577 58.5851 71.6921 58.5851C71.3264 58.5851 70.9757 58.6964 70.7172 58.8943C70.4586 59.0923 70.3134 59.3608 70.3134 59.6408V61.7522C69.2165 61.7522 68.1644 62.0858 67.3888 62.6798C66.6131 63.2737 66.1774 64.0792 66.1774 64.9192V67.0305C66.1774 67.8705 66.6131 68.676 67.3888 69.2699C68.1644 69.8639 69.2165 70.1975 70.3134 70.1975H73.0707C73.4364 70.1975 73.7871 70.3088 74.0456 70.5067C74.3042 70.7047 74.4494 70.9732 74.4494 71.2532V73.3646C74.4494 73.6445 74.3042 73.9131 74.0456 74.111C73.7871 74.309 73.4364 74.4202 73.0707 74.4202ZM86.1957 90.4665L57.9053 92.2759V89.6895C57.9154 88.098 57.2499 86.5471 56.0091 85.2703C54.7684 83.9935 53.0195 83.06 51.0258 82.6102L30.172 77.8216C29.9368 77.1509 29.4202 76.558 28.7017 76.1341C27.9833 75.7103 27.1028 75.479 26.1959 75.4759H4.1371C3.77145 75.4759 3.42078 75.5871 3.16223 75.7851C2.90368 75.9831 2.75842 76.2516 2.75842 76.5316L2.75842 99.7564C2.75842 100.036 2.90368 100.305 3.16223 100.503C3.42078 100.701 3.77145 100.812 4.1371 100.812H26.1959C26.9835 100.81 27.754 100.636 28.4169 100.31C29.0797 99.9846 29.6073 99.5206 29.9376 98.9731L51.9495 104.03C54.9408 104.721 58.1384 104.684 61.1011 103.924L87.9604 97.0687C88.9907 96.8077 89.8601 96.2664 90.4038 95.5472C90.9475 94.828 91.1276 93.9811 90.91 93.167C90.6924 92.353 90.0922 91.6283 89.2233 91.1305C88.3543 90.6328 87.277 90.3965 86.1957 90.4665ZM19.3025 98.7007H5.51577V77.5873H19.3025V98.7007ZM27.5745 97.6451C27.5745 97.9251 27.4293 98.1936 27.1707 98.3915C26.9122 98.5895 26.5615 98.7007 26.1959 98.7007H22.0598V77.5873H26.1959C26.5615 77.5873 26.9122 77.6985 27.1707 77.8965C27.4293 78.0944 27.5745 78.363 27.5745 78.6429V97.6451ZM87.0918 95.0629L60.2298 101.918C57.8057 102.541 55.1889 102.572 52.7408 102.007L30.3319 96.8597V80.0618L50.2344 84.6328C51.6578 84.955 52.9062 85.6221 53.7922 86.5339C54.6782 87.4457 55.154 88.553 55.148 89.6895V91.8621L43.2528 88.2179C43.0834 88.1608 42.9008 88.1304 42.7158 88.1286C42.5308 88.1267 42.3472 88.1533 42.1759 88.2069C42.0046 88.2605 41.8492 88.3399 41.7189 88.4405C41.5885 88.5411 41.486 88.6607 41.4173 88.7922C41.3486 88.9238 41.3152 89.0646 41.3191 89.2062C41.3229 89.3479 41.364 89.4875 41.4398 89.6167C41.5157 89.746 41.6247 89.8622 41.7604 89.9585C41.8961 90.0548 42.0558 90.1292 42.2298 90.1772L56.0166 94.3999H56.0524C56.1193 94.4137 56.1876 94.4236 56.2564 94.4295C56.3464 94.4499 56.4387 94.4633 56.5322 94.4696C56.5487 94.4696 56.5625 94.4696 56.5791 94.459C56.5956 94.4485 56.6232 94.459 56.648 94.459L86.4273 92.5588C86.8368 92.5301 87.2457 92.6179 87.5758 92.8056C87.9059 92.9932 88.1341 93.2675 88.2167 93.5759C88.2993 93.8843 88.2306 94.2052 88.0235 94.4772C87.8165 94.7492 87.4858 94.9532 87.0946 95.0502L87.0918 95.0629ZM71.6921 83.9213C75.5095 83.9213 79.2413 83.0545 82.4154 81.4305C85.5895 79.8065 88.0634 77.4983 89.5243 74.7977C90.9851 72.0971 91.3674 69.1255 90.6226 66.2585C89.8779 63.3916 88.0396 60.7582 85.3402 58.6912C82.6409 56.6243 79.2017 55.2167 75.4576 54.6464C71.7135 54.0761 67.8326 54.3688 64.3057 55.4875C60.7789 56.6061 57.7644 58.5004 55.6435 60.9309C53.5227 63.3613 52.3906 66.2188 52.3906 69.1419C52.3965 73.0602 54.4319 76.8169 58.0503 79.5876C61.6688 82.3583 66.5748 83.9168 71.6921 83.9213ZM71.6921 56.4738C74.9642 56.4738 78.1628 57.2168 80.8835 58.6087C83.6041 60.0007 85.7246 61.9792 86.9768 64.294C88.229 66.6088 88.5566 69.1559 87.9183 71.6133C87.2799 74.0707 85.7042 76.3279 83.3905 78.0996C81.0768 79.8712 78.1289 81.0777 74.9197 81.5665C71.7104 82.0553 68.384 81.8045 65.3609 80.8457C62.3379 79.8868 59.7541 78.2631 57.9362 76.1799C56.1183 74.0966 55.148 71.6474 55.148 69.1419C55.1531 65.7833 56.8978 62.5634 59.9993 60.1885C63.1008 57.8136 67.3059 56.4777 71.6921 56.4738Z\" fill=\"black\"><\/path><path d=\"M17.9291 20.0578H23.4438C23.8095 20.0578 24.1602 20.169 24.4187 20.367C24.6773 20.565 24.8225 20.8335 24.8225 21.1135C24.8225 21.3935 24.6773 21.662 24.4187 21.86C24.1602 22.0579 23.8095 22.1692 23.4438 22.1692H20.6865V24.2805C20.6865 24.5605 20.5412 24.829 20.2827 25.027C20.0241 25.225 19.6735 25.3362 19.3078 25.3362C18.9422 25.3362 18.5915 25.225 18.3329 25.027C18.0744 24.829 17.9291 24.5605 17.9291 24.2805V22.1692C16.8322 22.1692 15.7802 21.8355 15.0045 21.2416C14.2289 20.6476 13.7931 19.8421 13.7931 19.0021V16.8908C13.7931 16.0508 14.2289 15.2453 15.0045 14.6514C15.7802 14.0574 16.8322 13.7238 17.9291 13.7238H20.6865C21.0521 13.7238 21.4028 13.6125 21.6614 13.4146C21.9199 13.2166 22.0652 12.9481 22.0652 12.6681V10.5567C22.0652 10.2768 21.9199 10.0082 21.6614 9.81027C21.4028 9.6123 21.0521 9.50107 20.6865 9.50107H15.1718C14.8061 9.50107 14.4555 9.38985 14.1969 9.19187C13.9384 8.9939 13.7931 8.72538 13.7931 8.4454C13.7931 8.16542 13.9384 7.8969 14.1969 7.69892C14.4555 7.50095 14.8061 7.38973 15.1718 7.38973H17.9291V5.27838C17.9291 4.9984 18.0744 4.72988 18.3329 4.5319C18.5915 4.33393 18.9422 4.2227 19.3078 4.2227C19.6735 4.2227 20.0241 4.33393 20.2827 4.5319C20.5412 4.72988 20.6865 4.9984 20.6865 5.27838V7.38973C21.7834 7.38973 22.8354 7.72339 23.6111 8.31732C24.3867 8.91126 24.8225 9.7168 24.8225 10.5567V12.6681C24.8225 13.508 24.3867 14.3136 23.6111 14.9075C22.8354 15.5015 21.7834 15.8351 20.6865 15.8351H17.9291C17.5635 15.8351 17.2128 15.9463 16.9543 16.1443C16.6957 16.3423 16.5505 16.6108 16.5505 16.8908V19.0021C16.5505 19.2821 16.6957 19.5506 16.9543 19.7486C17.2128 19.9466 17.5635 20.0578 17.9291 20.0578ZM4.80417 36.1041L33.0945 37.9135V35.3271C33.0845 33.7356 33.75 32.1847 34.9907 30.9079C36.2315 29.6311 37.9804 28.6975 39.9741 28.2477L60.8279 23.4592C61.0631 22.7885 61.5797 22.1956 62.2982 21.7717C63.0166 21.3479 63.8971 21.1166 64.804 21.1135H86.8628C87.2284 21.1135 87.5791 21.2247 87.8377 21.4227C88.0962 21.6207 88.2415 21.8892 88.2415 22.1692V45.394C88.2415 45.674 88.0962 45.9425 87.8377 46.1405C87.5791 46.3384 87.2284 46.4497 86.8628 46.4497H64.804C64.0164 46.4478 63.2458 46.2737 62.583 45.9479C61.9202 45.6221 61.3926 45.1582 61.0623 44.6107L39.0504 49.6674C36.0591 50.3583 32.8615 50.3214 29.8988 49.5618L3.03947 42.7062C2.00917 42.4453 1.13973 41.9039 0.596052 41.1848C0.0523733 40.4656 -0.127745 39.6187 0.089852 38.8046C0.307449 37.9905 0.907633 37.2659 1.77658 36.7681C2.64553 36.2704 3.72283 36.0341 4.80417 36.1041ZM71.6974 44.3383H85.4841V23.2248H71.6974V44.3383ZM63.4253 43.2826C63.4253 43.5626 63.5706 43.8311 63.8291 44.0291C64.0877 44.2271 64.4384 44.3383 64.804 44.3383H68.94V23.2248H64.804C64.4384 23.2248 64.0877 23.3361 63.8291 23.534C63.5706 23.732 63.4253 24.0005 63.4253 24.2805V43.2826ZM3.90804 40.7005L30.7701 47.556C33.1942 48.1787 35.811 48.2097 38.259 47.6447L60.668 42.4972V25.6993L40.7655 30.2704C39.3421 30.5926 38.0937 31.2596 37.2077 32.1715C36.3217 33.0833 35.8459 34.1906 35.8519 35.3271V37.4997L47.7471 33.8555C47.9164 33.7984 48.0991 33.768 48.2841 33.7661C48.4691 33.7642 48.6527 33.7909 48.824 33.8445C48.9952 33.8981 49.1507 33.9775 49.281 34.0781C49.4114 34.1786 49.5139 34.2983 49.5826 34.4298C49.6513 34.5614 49.6847 34.7022 49.6808 34.8438C49.6769 34.9855 49.6359 35.1251 49.56 35.2543C49.4842 35.3835 49.3752 35.4998 49.2395 35.5961C49.1038 35.6924 48.9441 35.7668 48.7701 35.8148L34.9833 40.0375H34.9475C34.8805 40.0513 34.8123 40.0611 34.7434 40.0671C34.6535 40.0875 34.5611 40.1009 34.4677 40.1072C34.4512 40.1072 34.4374 40.1072 34.4208 40.0966C34.4043 40.0861 34.3767 40.0966 34.3519 40.0966L4.57256 38.1964C4.16312 38.1677 3.75422 38.2555 3.42408 38.4432C3.09394 38.6308 2.86574 38.9051 2.78314 39.2135C2.70053 39.5219 2.76933 39.8428 2.97636 40.1148C3.18339 40.3868 3.51412 40.5908 3.90528 40.6878L3.90804 40.7005ZM19.3078 29.5589C15.4904 29.5589 11.7586 28.6921 8.58452 27.0681C5.41042 25.4441 2.9365 23.1359 1.47562 20.4353C0.0147461 17.7347 -0.367486 14.763 0.377263 11.8961C1.12201 9.02919 2.9603 6.39575 5.65965 4.3288C8.359 2.26186 11.7982 0.854257 15.5423 0.283989C19.2864 -0.286278 23.1673 0.00640368 26.6941 1.12502C30.221 2.24364 33.2355 4.13796 35.3564 6.56843C37.4772 8.9989 38.6092 11.8563 38.6092 14.7794C38.6034 18.6978 36.568 22.4544 32.9495 25.2251C29.3311 27.9959 24.4251 29.5544 19.3078 29.5589ZM19.3078 2.11136C16.0357 2.11136 12.8371 2.85433 10.1164 4.24631C7.39576 5.6383 5.27526 7.61679 4.02308 9.93158C2.7709 12.2464 2.44327 14.7935 3.08163 17.2509C3.71998 19.7082 5.29565 21.9655 7.60938 23.7371C9.92311 25.5088 12.871 26.7153 16.0802 27.2041C19.2895 27.6929 22.6159 27.442 25.639 26.4832C28.662 25.5244 31.2458 23.9007 33.0637 21.8175C34.8816 19.7342 35.8519 17.285 35.8519 14.7794C35.8468 11.4209 34.1021 8.20095 31.0006 5.82607C27.8991 3.45119 23.694 2.11527 19.3078 2.11136Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed vklad\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBez provize\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6074ca4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6074ca4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ed0a8f\" data-id=\"9ed0a8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f42c72 elementor-widget elementor-widget-html\" data-id=\"9f42c72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- TradingView Widget BEGIN -->\n<div class=\"tradingview-widget-container\">\n  <div class=\"tradingview-widget-container__widget\"><\/div>\n  <div class=\"tradingview-widget-copyright\"><a href=\"https:\/\/in.tradingview.com\/\" rel=\"noopener nofollow\" target=\"_blank\"><span class=\"blue-text\"><\/span><\/a><\/div>\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-ticker-tape.js\" async>\n  {\n  \"symbols\": [\n    {\n      \"proName\": \"FOREXCOM:SPXUSD\",\n      \"title\": \"S&P 500\"\n    },\n    {\n      \"proName\": \"FOREXCOM:NSXUSD\",\n      \"title\": \"US 100\"\n    },\n    {\n      \"proName\": \"FX_IDC:EURUSD\",\n      \"title\": \"EUR to USD\"\n    },\n    {\n      \"description\": \"AUD to CHF\",\n      \"proName\": \"OANDA:AUDCHF\"\n    },\n    {\n      \"description\": \"FXCCM\",\n      \"proName\": \"FX:EURUSD\"\n    },\n    {\n      \"description\": \"OANDA\",\n      \"proName\": \"OANDA:EURUSD\"\n    },\n    {\n      \"description\": \"CAPITALCOM\",\n      \"proName\": \"CAPITALCOM:USDCAD\"\n    }\n  ],\n  \"showSymbolLogo\": true,\n  \"colorTheme\": \"light\",\n  \"isTransparent\": true,\n  \"displayMode\": \"regular\",\n  \"locale\": \"in\"\n}\n  <\/script>\n<\/div>\n<!-- TradingView Widget END -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f2fd09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2fd09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5cc75d\" data-id=\"f5cc75d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f08c282 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f08c282\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3113ee8\" data-id=\"3113ee8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca92fbf elementor-widget elementor-widget-heading\" data-id=\"ca92fbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Na\u0161e obchodn\u00ed v\u00fdhody\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c94bf5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5c94bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"45\" viewBox=\"0 0 44 45\" fill=\"none\"><path d=\"M16.8917 20.4909C16.4763 20.0756 15.913 19.8422 15.3256 19.8422C14.7382 19.8422 14.1749 20.0756 13.7595 20.4909C13.3442 20.9062 13.1108 21.4696 13.1108 22.057C13.1108 22.6444 13.3442 23.2077 13.7595 23.623L20.3767 30.2402C20.5828 30.4447 20.8273 30.6064 21.096 30.7162C21.3647 30.8259 21.6525 30.8816 21.9428 30.8799C22.2447 30.8703 22.5415 30.7988 22.8147 30.6698C23.0879 30.5408 23.3317 30.357 23.5309 30.1299L38.971 12.4841C39.3275 12.0415 39.4994 11.4783 39.4509 10.912C39.4023 10.3458 39.137 9.8201 38.7104 9.44464C38.2837 9.06917 37.7286 8.87289 37.1607 8.89672C36.5929 8.92055 36.0561 9.16265 35.6624 9.57255L21.9428 25.4538L16.8917 20.4909Z\" fill=\"#37F935\"><\/path><path d=\"M41.7943 19.8516C41.2093 19.8516 40.6482 20.0839 40.2346 20.4976C39.8209 20.9112 39.5885 21.4723 39.5885 22.0573C39.5885 26.7372 37.7294 31.2255 34.4202 34.5348C31.111 37.844 26.6227 39.7031 21.9427 39.7031C18.4579 39.7015 15.0515 38.6681 12.1532 36.7332C9.25483 34.7983 6.99432 32.0485 5.65667 28.8306C4.31902 25.6127 3.96413 22.0707 4.63676 18.6514C5.30938 15.2321 6.9794 12.0885 9.43623 9.61697C11.07 7.96132 13.0176 6.64816 15.1651 5.75433C17.3125 4.86051 19.6167 4.40398 21.9427 4.41146C23.3532 4.42029 24.7584 4.583 26.1336 4.89672C26.4214 4.98573 26.7243 5.01485 27.0238 4.9823C27.3232 4.94974 27.6129 4.85619 27.8748 4.70742C28.1367 4.55864 28.3654 4.3578 28.5467 4.11726C28.728 3.87673 28.8582 3.6016 28.9291 3.30884C29 3.01609 29.0102 2.7119 28.9591 2.41505C28.908 2.1182 28.7966 1.83496 28.6318 1.58281C28.467 1.33066 28.2523 1.11493 28.0009 0.948929C27.7496 0.782927 27.4669 0.670168 27.1703 0.617604C25.4568 0.214491 23.703 0.00729528 21.9427 0C17.5849 0.0226386 13.3315 1.33561 9.71922 3.77323C6.10692 6.21085 3.29762 9.66387 1.64586 13.6965C-0.00590584 17.7292 -0.426116 22.1608 0.438256 26.432C1.30263 30.7033 3.41285 34.6228 6.50261 37.6959C10.598 41.7931 16.1497 44.101 21.9427 44.1146C27.7927 44.1146 33.403 41.7907 37.5396 37.6541C41.6761 33.5176 44 27.9072 44 22.0573C44 21.4723 43.7676 20.9112 43.354 20.4976C42.9403 20.0839 42.3793 19.8516 41.7943 19.8516Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Finan\u010dn\u00ed prost\u0159edky obchodn\u00edka jsou vysoce zabezpe\u010deny na odd\u011blen\u00fdch bankovn\u00edch \u00fa\u010dtech, co\u017e zaji\u0161\u0165uje maxim\u00e1ln\u00ed ochranu klienta.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"45\" viewBox=\"0 0 44 45\" fill=\"none\"><path d=\"M16.8917 20.4909C16.4763 20.0756 15.913 19.8422 15.3256 19.8422C14.7382 19.8422 14.1749 20.0756 13.7595 20.4909C13.3442 20.9062 13.1108 21.4696 13.1108 22.057C13.1108 22.6444 13.3442 23.2077 13.7595 23.623L20.3767 30.2402C20.5828 30.4447 20.8273 30.6064 21.096 30.7162C21.3647 30.8259 21.6525 30.8816 21.9428 30.8799C22.2447 30.8703 22.5415 30.7988 22.8147 30.6698C23.0879 30.5408 23.3317 30.357 23.5309 30.1299L38.971 12.4841C39.3275 12.0415 39.4994 11.4783 39.4509 10.912C39.4023 10.3458 39.137 9.8201 38.7104 9.44464C38.2837 9.06917 37.7286 8.87289 37.1607 8.89672C36.5929 8.92055 36.0561 9.16265 35.6624 9.57255L21.9428 25.4538L16.8917 20.4909Z\" fill=\"#37F935\"><\/path><path d=\"M41.7943 19.8516C41.2093 19.8516 40.6482 20.0839 40.2346 20.4976C39.8209 20.9112 39.5885 21.4723 39.5885 22.0573C39.5885 26.7372 37.7294 31.2255 34.4202 34.5348C31.111 37.844 26.6227 39.7031 21.9427 39.7031C18.4579 39.7015 15.0515 38.6681 12.1532 36.7332C9.25483 34.7983 6.99432 32.0485 5.65667 28.8306C4.31902 25.6127 3.96413 22.0707 4.63676 18.6514C5.30938 15.2321 6.9794 12.0885 9.43623 9.61697C11.07 7.96132 13.0176 6.64816 15.1651 5.75433C17.3125 4.86051 19.6167 4.40398 21.9427 4.41146C23.3532 4.42029 24.7584 4.583 26.1336 4.89672C26.4214 4.98573 26.7243 5.01485 27.0238 4.9823C27.3232 4.94974 27.6129 4.85619 27.8748 4.70742C28.1367 4.55864 28.3654 4.3578 28.5467 4.11726C28.728 3.87673 28.8582 3.6016 28.9291 3.30884C29 3.01609 29.0102 2.7119 28.9591 2.41505C28.908 2.1182 28.7966 1.83496 28.6318 1.58281C28.467 1.33066 28.2523 1.11493 28.0009 0.948929C27.7496 0.782927 27.4669 0.670168 27.1703 0.617604C25.4568 0.214491 23.703 0.00729528 21.9427 0C17.5849 0.0226386 13.3315 1.33561 9.71922 3.77323C6.10692 6.21085 3.29762 9.66387 1.64586 13.6965C-0.00590584 17.7292 -0.426116 22.1608 0.438256 26.432C1.30263 30.7033 3.41285 34.6228 6.50261 37.6959C10.598 41.7931 16.1497 44.101 21.9427 44.1146C27.7927 44.1146 33.403 41.7907 37.5396 37.6541C41.6761 33.5176 44 27.9072 44 22.0573C44 21.4723 43.7676 20.9112 43.354 20.4976C42.9403 20.0839 42.3793 19.8516 41.7943 19.8516Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nab\u00edz\u00edme finan\u010dn\u00ed slu\u017eby ve v\u00edce ne\u017e 80 zem\u00edch sv\u011bta.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"45\" viewBox=\"0 0 44 45\" fill=\"none\"><path d=\"M16.8917 20.4909C16.4763 20.0756 15.913 19.8422 15.3256 19.8422C14.7382 19.8422 14.1749 20.0756 13.7595 20.4909C13.3442 20.9062 13.1108 21.4696 13.1108 22.057C13.1108 22.6444 13.3442 23.2077 13.7595 23.623L20.3767 30.2402C20.5828 30.4447 20.8273 30.6064 21.096 30.7162C21.3647 30.8259 21.6525 30.8816 21.9428 30.8799C22.2447 30.8703 22.5415 30.7988 22.8147 30.6698C23.0879 30.5408 23.3317 30.357 23.5309 30.1299L38.971 12.4841C39.3275 12.0415 39.4994 11.4783 39.4509 10.912C39.4023 10.3458 39.137 9.8201 38.7104 9.44464C38.2837 9.06917 37.7286 8.87289 37.1607 8.89672C36.5929 8.92055 36.0561 9.16265 35.6624 9.57255L21.9428 25.4538L16.8917 20.4909Z\" fill=\"#37F935\"><\/path><path d=\"M41.7943 19.8516C41.2093 19.8516 40.6482 20.0839 40.2346 20.4976C39.8209 20.9112 39.5885 21.4723 39.5885 22.0573C39.5885 26.7372 37.7294 31.2255 34.4202 34.5348C31.111 37.844 26.6227 39.7031 21.9427 39.7031C18.4579 39.7015 15.0515 38.6681 12.1532 36.7332C9.25483 34.7983 6.99432 32.0485 5.65667 28.8306C4.31902 25.6127 3.96413 22.0707 4.63676 18.6514C5.30938 15.2321 6.9794 12.0885 9.43623 9.61697C11.07 7.96132 13.0176 6.64816 15.1651 5.75433C17.3125 4.86051 19.6167 4.40398 21.9427 4.41146C23.3532 4.42029 24.7584 4.583 26.1336 4.89672C26.4214 4.98573 26.7243 5.01485 27.0238 4.9823C27.3232 4.94974 27.6129 4.85619 27.8748 4.70742C28.1367 4.55864 28.3654 4.3578 28.5467 4.11726C28.728 3.87673 28.8582 3.6016 28.9291 3.30884C29 3.01609 29.0102 2.7119 28.9591 2.41505C28.908 2.1182 28.7966 1.83496 28.6318 1.58281C28.467 1.33066 28.2523 1.11493 28.0009 0.948929C27.7496 0.782927 27.4669 0.670168 27.1703 0.617604C25.4568 0.214491 23.703 0.00729528 21.9427 0C17.5849 0.0226386 13.3315 1.33561 9.71922 3.77323C6.10692 6.21085 3.29762 9.66387 1.64586 13.6965C-0.00590584 17.7292 -0.426116 22.1608 0.438256 26.432C1.30263 30.7033 3.41285 34.6228 6.50261 37.6959C10.598 41.7931 16.1497 44.101 21.9427 44.1146C27.7927 44.1146 33.403 41.7907 37.5396 37.6541C41.6761 33.5176 44 27.9072 44 22.0573C44 21.4723 43.7676 20.9112 43.354 20.4976C42.9403 20.0839 42.3793 19.8516 41.7943 19.8516Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Flexibiln\u00ed metody: Visa, MasterCard, bankovn\u00ed p\u0159evod. Bezpe\u010dn\u00e9 transakce, rychl\u00e9 v\u00fdb\u011bry bez dal\u0161\u00edch poplatk\u016f.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"45\" viewBox=\"0 0 44 45\" fill=\"none\"><path d=\"M16.8917 20.4909C16.4763 20.0756 15.913 19.8422 15.3256 19.8422C14.7382 19.8422 14.1749 20.0756 13.7595 20.4909C13.3442 20.9062 13.1108 21.4696 13.1108 22.057C13.1108 22.6444 13.3442 23.2077 13.7595 23.623L20.3767 30.2402C20.5828 30.4447 20.8273 30.6064 21.096 30.7162C21.3647 30.8259 21.6525 30.8816 21.9428 30.8799C22.2447 30.8703 22.5415 30.7988 22.8147 30.6698C23.0879 30.5408 23.3317 30.357 23.5309 30.1299L38.971 12.4841C39.3275 12.0415 39.4994 11.4783 39.4509 10.912C39.4023 10.3458 39.137 9.8201 38.7104 9.44464C38.2837 9.06917 37.7286 8.87289 37.1607 8.89672C36.5929 8.92055 36.0561 9.16265 35.6624 9.57255L21.9428 25.4538L16.8917 20.4909Z\" fill=\"#37F935\"><\/path><path d=\"M41.7943 19.8516C41.2093 19.8516 40.6482 20.0839 40.2346 20.4976C39.8209 20.9112 39.5885 21.4723 39.5885 22.0573C39.5885 26.7372 37.7294 31.2255 34.4202 34.5348C31.111 37.844 26.6227 39.7031 21.9427 39.7031C18.4579 39.7015 15.0515 38.6681 12.1532 36.7332C9.25483 34.7983 6.99432 32.0485 5.65667 28.8306C4.31902 25.6127 3.96413 22.0707 4.63676 18.6514C5.30938 15.2321 6.9794 12.0885 9.43623 9.61697C11.07 7.96132 13.0176 6.64816 15.1651 5.75433C17.3125 4.86051 19.6167 4.40398 21.9427 4.41146C23.3532 4.42029 24.7584 4.583 26.1336 4.89672C26.4214 4.98573 26.7243 5.01485 27.0238 4.9823C27.3232 4.94974 27.6129 4.85619 27.8748 4.70742C28.1367 4.55864 28.3654 4.3578 28.5467 4.11726C28.728 3.87673 28.8582 3.6016 28.9291 3.30884C29 3.01609 29.0102 2.7119 28.9591 2.41505C28.908 2.1182 28.7966 1.83496 28.6318 1.58281C28.467 1.33066 28.2523 1.11493 28.0009 0.948929C27.7496 0.782927 27.4669 0.670168 27.1703 0.617604C25.4568 0.214491 23.703 0.00729528 21.9427 0C17.5849 0.0226386 13.3315 1.33561 9.71922 3.77323C6.10692 6.21085 3.29762 9.66387 1.64586 13.6965C-0.00590584 17.7292 -0.426116 22.1608 0.438256 26.432C1.30263 30.7033 3.41285 34.6228 6.50261 37.6959C10.598 41.7931 16.1497 44.101 21.9427 44.1146C27.7927 44.1146 33.403 41.7907 37.5396 37.6541C41.6761 33.5176 44 27.9072 44 22.0573C44 21.4723 43.7676 20.9112 43.354 20.4976C42.9403 20.0839 42.3793 19.8516 41.7943 19.8516Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vytvo\u0159te si vlastn\u00ed portfolio obchodn\u00edch syst\u00e9m\u016f a obchodujte efektivn\u011b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"45\" viewBox=\"0 0 44 45\" fill=\"none\"><path d=\"M16.8917 20.4909C16.4763 20.0756 15.913 19.8422 15.3256 19.8422C14.7382 19.8422 14.1749 20.0756 13.7595 20.4909C13.3442 20.9062 13.1108 21.4696 13.1108 22.057C13.1108 22.6444 13.3442 23.2077 13.7595 23.623L20.3767 30.2402C20.5828 30.4447 20.8273 30.6064 21.096 30.7162C21.3647 30.8259 21.6525 30.8816 21.9428 30.8799C22.2447 30.8703 22.5415 30.7988 22.8147 30.6698C23.0879 30.5408 23.3317 30.357 23.5309 30.1299L38.971 12.4841C39.3275 12.0415 39.4994 11.4783 39.4509 10.912C39.4023 10.3458 39.137 9.8201 38.7104 9.44464C38.2837 9.06917 37.7286 8.87289 37.1607 8.89672C36.5929 8.92055 36.0561 9.16265 35.6624 9.57255L21.9428 25.4538L16.8917 20.4909Z\" fill=\"#37F935\"><\/path><path d=\"M41.7943 19.8516C41.2093 19.8516 40.6482 20.0839 40.2346 20.4976C39.8209 20.9112 39.5885 21.4723 39.5885 22.0573C39.5885 26.7372 37.7294 31.2255 34.4202 34.5348C31.111 37.844 26.6227 39.7031 21.9427 39.7031C18.4579 39.7015 15.0515 38.6681 12.1532 36.7332C9.25483 34.7983 6.99432 32.0485 5.65667 28.8306C4.31902 25.6127 3.96413 22.0707 4.63676 18.6514C5.30938 15.2321 6.9794 12.0885 9.43623 9.61697C11.07 7.96132 13.0176 6.64816 15.1651 5.75433C17.3125 4.86051 19.6167 4.40398 21.9427 4.41146C23.3532 4.42029 24.7584 4.583 26.1336 4.89672C26.4214 4.98573 26.7243 5.01485 27.0238 4.9823C27.3232 4.94974 27.6129 4.85619 27.8748 4.70742C28.1367 4.55864 28.3654 4.3578 28.5467 4.11726C28.728 3.87673 28.8582 3.6016 28.9291 3.30884C29 3.01609 29.0102 2.7119 28.9591 2.41505C28.908 2.1182 28.7966 1.83496 28.6318 1.58281C28.467 1.33066 28.2523 1.11493 28.0009 0.948929C27.7496 0.782927 27.4669 0.670168 27.1703 0.617604C25.4568 0.214491 23.703 0.00729528 21.9427 0C17.5849 0.0226386 13.3315 1.33561 9.71922 3.77323C6.10692 6.21085 3.29762 9.66387 1.64586 13.6965C-0.00590584 17.7292 -0.426116 22.1608 0.438256 26.432C1.30263 30.7033 3.41285 34.6228 6.50261 37.6959C10.598 41.7931 16.1497 44.101 21.9427 44.1146C27.7927 44.1146 33.403 41.7907 37.5396 37.6541C41.6761 33.5176 44 27.9072 44 22.0573C44 21.4723 43.7676 20.9112 43.354 20.4976C42.9403 20.0839 42.3793 19.8516 41.7943 19.8516Z\" fill=\"black\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rychl\u00fd p\u0159\u00edstup k nejlep\u0161\u00edm cenov\u00fdm mo\u017enostem a tr\u017en\u00ed likvidit\u011b protistran.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca36bee elementor-widget elementor-widget-button\" data-id=\"ca36bee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/zaregistrujte-se\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zaregistrujte se<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a18214b\" data-id=\"a18214b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b14c900 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b14c900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1702\" height=\"1300\" src=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/Group-39950.webp\" class=\"attachment-large size-large wp-image-1613\" alt=\"\" srcset=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/Group-39950.webp 1702w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/Group-39950-768x587.webp 768w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/Group-39950-1536x1173.webp 1536w\" sizes=\"(max-width: 1702px) 100vw, 1702px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2b8c9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2b8c9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ea1b46\" data-id=\"5ea1b46\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d36d972 elementor-widget elementor-widget-heading\" data-id=\"d36d972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Pro\u010d si vybrat pr\u00e1v\u011b n\u00e1s?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e87fd6b elementor-widget elementor-widget-text-editor\" data-id=\"e87fd6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nab\u00edz\u00edme dobr\u00e9 mo\u017enosti pro obchodov\u00e1n\u00ed na Forexu. V\u0161echny obchodn\u00ed platformy uveden\u00e9 v t\u00e9to kategorii si zaslou\u017e\u00ed pozornost. V\u0161echny termin\u00e1ly jsou kompatibiln\u00ed s po\u010d\u00edta\u010di a modern\u00edmi mobiln\u00edmi p\u0159\u00edstroji. To neomezuje jejich \u010dinnost, ale umo\u017e\u0148uje v\u00e1m obchodovat kdykoli se v\u00e1m to hod\u00ed. M\u016f\u017eete tak\u00e9 pou\u017e\u00edt webovou verzi. Tento zp\u016fsob je vhodn\u00fd pro ty, kte\u0159\u00ed cht\u011bj\u00ed u\u0161et\u0159it \u010das.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12482bb elementor-widget elementor-widget-button\" data-id=\"12482bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/zaregistrujte-se\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zaregistrujte se<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-699904d\" data-id=\"699904d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-944280d elementor-widget elementor-widget-heading\" data-id=\"944280d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Prvot\u0159\u00eddn\u00ed slu\u017eby\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5df9294 elementor-widget elementor-widget-text-editor\" data-id=\"5df9294\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Poskytujeme p\u0159\u00edstup k pohodln\u00fdm obchodn\u00edm platform\u00e1m, kter\u00e9 jsou vhodn\u00e9 pro u\u017eivatele s r\u016fznou \u00farovn\u00ed znalost\u00ed a zku\u0161enost\u00ed. Klientsk\u00fd servis zahrnuje pokro\u010dil\u00e9 \u0161kolen\u00ed mo\u017en\u00e9 pro studenty i d\u016fchodce, po kter\u00e9m m\u016f\u017eete vyd\u011bl\u00e1vat pen\u00edze v doprovodu osobn\u00edho mana\u017eera a analytika.<\/span><\/p><p><span style=\"font-weight: 400;\">S Portal Invest Trade se m\u016f\u017eete spolehnout na efektivn\u00ed obchodov\u00e1n\u00ed, co\u017e dokazuj\u00ed na\u0161e rostouc\u00ed \u010d\u00edsla.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc24df5 elementor-widget elementor-widget-button\" data-id=\"bc24df5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/zaregistrujte-se\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zaregistrujte se<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa35c9e elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa35c9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6cc9fb\" data-id=\"c6cc9fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8168d20 elementor-widget elementor-widget-heading\" data-id=\"8168d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ZA\u010cN\u011aTE V MAL\u00c9M. <br>MYSLET VELICE.<\/br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-375c9d5 elementor-widget elementor-widget-text-editor\" data-id=\"375c9d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Jako online investi\u010dn\u00ed makl\u00e9\u0159 spojujeme v\u0161echny va\u0161e investi\u010dn\u00ed pot\u0159eby. Na port\u00e1lu Invest Trade se sna\u017e\u00edme spojit v\u00e1\u0161 obchodn\u00ed z\u00e1\u017eitek s va\u0161\u00ed spokojenost\u00ed jako hlavn\u00edm c\u00edlem. S n\u00e1mi si m\u016f\u017eete vyzkou\u0161et nejnov\u011bj\u0161\u00ed obchodn\u00ed technologie. otev\u0159en\u00edm \u00fa\u010dtu u n\u00e1s z\u00edsk\u00e1te v\u00fdhody na\u0161ich vynikaj\u00edc\u00edch obchodn\u00edch podm\u00ednek. Za\u017eijte obchodov\u00e1n\u00ed nov\u00e9 generace s Portal Invest Trade, obchodujte s vy\u0161\u0161\u00ed finan\u010dn\u00ed v\u00fd\u0161\u00ed<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f235597 elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"f235597\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/zaregistrujte-se\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Otev\u0159en\u00ed obchodn\u00edho \u00fa\u010dtu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ee4314\" data-id=\"7ee4314\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baf9a0d elementor-widget elementor-widget-image\" data-id=\"baf9a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1854\" height=\"1506\" src=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/platforms-overview-metatrader-compress-v2-1.webp\" class=\"attachment-large size-large wp-image-1625\" alt=\"\" srcset=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/platforms-overview-metatrader-compress-v2-1.webp 1854w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/platforms-overview-metatrader-compress-v2-1-768x624.webp 768w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/platforms-overview-metatrader-compress-v2-1-1536x1248.webp 1536w\" sizes=\"(max-width: 1854px) 100vw, 1854px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18454e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18454e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a2cb1a\" data-id=\"1a2cb1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b8275d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b8275d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-171b39a\" data-id=\"171b39a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d473e5 elementor-widget elementor-widget-heading\" data-id=\"5d473e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Forex<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a43a6b elementor-widget elementor-widget-text-editor\" data-id=\"9a43a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Obchodujte 62 m\u011bnov\u00fdch p\u00e1r\u016f, v\u010detn\u011b hlavn\u00edch, vedlej\u0161\u00edch a exotick\u00fdch, s velmi n\u00edzk\u00fdmi spready a rychl\u00fdm proveden\u00edm.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bdeccd elementor-widget elementor-widget-button\" data-id=\"0bdeccd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/trhy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trh<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d66cc92\" data-id=\"d66cc92\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-522730d elementor-widget elementor-widget-heading\" data-id=\"522730d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DLUHOPISY\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4748f38 elementor-widget elementor-widget-text-editor\" data-id=\"4748f38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Vyu\u017eijte inverzn\u00edho vztahu mezi \u00farokov\u00fdmi sazbami a cenami dluhopis\u016f a vyu\u017eijte stability st\u00e1tn\u00edch dluhopis\u016f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-682c586 elementor-widget elementor-widget-button\" data-id=\"682c586\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/trhy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trh<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-62d6417\" data-id=\"62d6417\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bd9695 elementor-widget elementor-widget-heading\" data-id=\"5bd9695\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">STOCk<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39d1240 elementor-widget elementor-widget-text-editor\" data-id=\"39d1240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Z\u00edskejte p\u0159\u00edstup k hlavn\u00edm mezin\u00e1rodn\u00edm akciov\u00fdm index\u016fm a rop\u011b bez proviz\u00ed nebo opakovan\u00fdch kotac\u00ed a bez skryt\u00fdch p\u0159ir\u00e1\u017eek.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f910ba elementor-widget elementor-widget-button\" data-id=\"8f910ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/trhy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trh<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b40977b\" data-id=\"b40977b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f3e6bb elementor-widget elementor-widget-heading\" data-id=\"3f3e6bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">KOVY\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22101b5 elementor-widget elementor-widget-text-editor\" data-id=\"22101b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Spekulujte na pohyb cen zlata a st\u0159\u00edbra v\u016f\u010di americk\u00e9mu dolaru a diverzifikujte sv\u00e9 obchodn\u00ed portfolio.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3592c5d elementor-widget elementor-widget-button\" data-id=\"3592c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cz\/trhy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trh<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4f304b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4f304b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c179b62\" data-id=\"c179b62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3370fa0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3370fa0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bd65e09\" data-id=\"bd65e09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a7d4bc elementor-widget elementor-widget-image\" data-id=\"6a7d4bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1738\" height=\"1516\" src=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1.webp\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1629\" alt=\"\" srcset=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1.webp 1738w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1-768x670.webp 768w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1-1536x1340.webp 1536w\" sizes=\"(max-width: 1738px) 100vw, 1738px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f0fc1a4\" data-id=\"f0fc1a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e2f6da elementor-widget elementor-widget-heading\" data-id=\"4e2f6da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> 4 kroky pro registraci na port\u00e1lu Invest Trade <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55be49d elementor-widget elementor-widget-text-editor\" data-id=\"55be49d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Na\u0161e r\u016fzn\u00e9 typy exekuc\u00ed jsou pokro\u010dil\u00e9 a zaji\u0161\u0165uj\u00ed v\u00e1m nejni\u017e\u0161\u00ed mo\u017en\u00e9 plovouc\u00ed sazby. Poskytujeme flexibiln\u00ed rozsah p\u00e1kov\u00e9ho efektu v z\u00e1vislosti na typu \u00fa\u010dtu, kter\u00fd si vyberete.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-143c581 elementor-widget elementor-widget-toggle\" data-id=\"143c581\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2121\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2121\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Registrace<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2121\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2121\"><p><span style=\"font-weight: 400;\">Vyberte si pl\u00e1n \u00fa\u010dtu a zaregistrujte se pomoc\u00ed sv\u00e9ho jm\u00e9na a e-mailov\u00e9 adresy.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2122\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2122\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ov\u011b\u0159ov\u00e1n\u00ed<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2122\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2122\"><p><span style=\"font-weight: 400;\">P\u0159idajte pot\u0159ebn\u00e9 doklady k prok\u00e1z\u00e1n\u00ed toto\u017enosti a ov\u011b\u0159it je v mezin\u00e1rodn\u00edm finan\u010dn\u00edm syst\u00e9mu v souladu s pravidly finan\u010dn\u00edch trh\u016f.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2123\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2123\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Financov\u00e1n\u00ed<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2123\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2123\"><p><span style=\"font-weight: 400;\">Aktivujte sv\u016fj \u00fa\u010det a za\u010dn\u011bte obchodovat od pouh\u00fdch 250 \u20ac<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2124\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2124\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Obchodov\u00e1n\u00ed<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2124\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2124\"><p><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">P\u0159ihlaste se a za\u010dn\u011bte obchodovat v\u00edce ne\u017e 200 n\u00e1stroj\u016f!<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21f4e28 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"21f4e28\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a921715\" data-id=\"a921715\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f45e6cf elementor-widget elementor-widget-html\" data-id=\"f45e6cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- TradingView Widget BEGIN -->\n<div class=\"tradingview-widget-container\">\n  <div class=\"tradingview-widget-container__widget\"><\/div>\n  <div class=\"tradingview-widget-copyright\"><a href=\"https:\/\/in.tradingview.com\/\" rel=\"noopener nofollow\" target=\"_blank\"><span class=\"blue-text\"><\/span><\/a><\/div>\n  <script type=\"text\/javascript\" src=\"https:\/\/s3.tradingview.com\/external-embedding\/embed-widget-ticker-tape.js\" async>\n  {\n  \"symbols\": [\n    {\n      \"proName\": \"FOREXCOM:SPXUSD\",\n      \"title\": \"S&P 500\"\n    },\n    {\n      \"proName\": \"FOREXCOM:NSXUSD\",\n      \"title\": \"US 100\"\n    },\n    {\n      \"proName\": \"FX_IDC:EURUSD\",\n      \"title\": \"EUR to USD\"\n    },\n    {\n      \"description\": \"AUD to CHF\",\n      \"proName\": \"OANDA:AUDCHF\"\n    },\n    {\n      \"description\": \"FXCCM\",\n      \"proName\": \"FX:EURUSD\"\n    },\n    {\n      \"description\": \"OANDA\",\n      \"proName\": \"OANDA:EURUSD\"\n    },\n    {\n      \"description\": \"CAPITALCOM\",\n      \"proName\": \"CAPITALCOM:USDCAD\"\n    }\n  ],\n  \"showSymbolLogo\": true,\n  \"colorTheme\": \"light\",\n  \"isTransparent\": true,\n  \"displayMode\": \"regular\",\n  \"locale\": \"in\"\n}\n  <\/script>\n<\/div>\n<!-- TradingView Widget END -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Port\u00e1l Invest Trade V\u00edtejte u profesion\u00e1l\u016f! Zaregistrujte sePort\u00e1l Invest Trade Obchodujte jako profesion\u00e1l \u00da\u010dty Previous slide Next slide Dostupn\u00e1 aktiva 300 + nejobl\u00edben\u011bj\u0161\u00ed aktiva Minim\u00e1ln\u00ed velikost obchodu Ka\u017ed\u00fd si m\u016f\u017ee dovolit investovat Minim\u00e1ln\u00ed vklad Bez provize Dostupn\u00e1 aktiva 300 + nejobl\u00edben\u011bj\u0161\u00ed aktiva Minim\u00e1ln\u00ed velikost obchodu Ka\u017ed\u00fd si m\u016f\u017ee dovolit investovat Minim\u00e1ln\u00ed vklad Bez provize Na\u0161e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-803","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages\/803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/comments?post=803"}],"version-history":[{"count":29,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages\/803\/revisions"}],"predecessor-version":[{"id":1866,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages\/803\/revisions\/1866"}],"wp:attachment":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/media?parent=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}