{"id":901,"date":"2023-07-27T21:26:59","date_gmt":"2023-07-27T21:26:59","guid":{"rendered":"https:\/\/ghostwhite-loris-458768.hostingersite.com\/?page_id=901"},"modified":"2024-03-05T14:53:57","modified_gmt":"2024-03-05T14:53:57","slug":"ucty","status":"publish","type":"page","link":"https:\/\/portalinv.org\/cs\/ucty\/","title":{"rendered":"\u00a0\u00da\u010dty"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"901\" class=\"elementor elementor-901 elementor-170\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-634597a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"634597a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18c3d80\" data-id=\"18c3d80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-810bdbf elementor-widget elementor-widget-heading\" data-id=\"810bdbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> \u00da\u010dty\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-786de53 elementor-widget elementor-widget-heading\" data-id=\"786de53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Port\u00e1l Invest Trade \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6070f3f elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"6070f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/ghostwhite-loris-458768.hostingersite.com\/cs\/prihlasit-se\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Otev\u0159en\u00fd \u00fa\u010det<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a14a74a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a14a74a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9dba5b1\" data-id=\"9dba5b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a0c0f5 elementor-tabs-alignment-center elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"5a0c0f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9441\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9441\" aria-expanded=\"false\">Test 250\u20ac<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9442\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9442\" aria-expanded=\"false\">Basic 3000\u20ac<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9443\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9443\" aria-expanded=\"false\">Standard 10 000\u20ac<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9444\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9444\" aria-expanded=\"false\">Standard+ 25 000\u20ac<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9445\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9445\" aria-expanded=\"false\">Advanced 50 000\u20ac<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9446\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9446\" aria-expanded=\"false\">Pro Account 100 000\u20ac<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-9447\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9447\" aria-expanded=\"false\">Vip 250 000\u20ac<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-9441\" aria-expanded=\"false\">Test 250\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9441\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9441\" tabindex=\"0\" hidden=\"false\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"909\" class=\"elementor elementor-909 elementor-509\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf2417d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf2417d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19ca624\" data-id=\"19ca624\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e607ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e607ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a2f295\" data-id=\"7a2f295\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e153c2 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"6e153c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c08556f\" data-id=\"c08556f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9afb113 elementor-widget elementor-widget-heading\" data-id=\"9afb113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 : 100<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22110b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22110b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9286060\" data-id=\"9286060\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40fa2be elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"40fa2be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-80180aa\" data-id=\"80180aa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d04f5f elementor-widget elementor-widget-heading\" data-id=\"3d04f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.6 Body\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a7a2ac5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7a2ac5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-85e855f\" data-id=\"85e855f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eda24d9 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"eda24d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41d3205\" data-id=\"41d3205\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56e00ff elementor-widget elementor-widget-heading\" data-id=\"56e00ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">7  Dny<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1165e2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1165e2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2bba35e\" data-id=\"2bba35e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8254cf7 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"8254cf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bb14502\" data-id=\"bb14502\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23cd043 elementor-widget elementor-widget-heading\" data-id=\"23cd043\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-96c2666\" data-id=\"96c2666\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7878886 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7878886\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87a5b65\" data-id=\"87a5b65\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f1bc30 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7f1bc30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-757c251\" data-id=\"757c251\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dab044 elementor-widget elementor-widget-heading\" data-id=\"2dab044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u011bnov\u00e9 p\u00e1ry\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-09cbc07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09cbc07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44cd5c8\" data-id=\"44cd5c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08da1f elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b08da1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a8d7e8b\" data-id=\"a8d7e8b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-baf95d4 elementor-widget elementor-widget-heading\" data-id=\"baf95d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-580b31d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"580b31d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c220f1f\" data-id=\"c220f1f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47b5cdb elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"47b5cdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4bff7b9\" data-id=\"4bff7b9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e57dec elementor-widget elementor-widget-heading\" data-id=\"6e57dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8cd589d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8cd589d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4ac8030\" data-id=\"4ac8030\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10f605a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"10f605a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30e3ded\" data-id=\"30e3ded\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2556b60 elementor-widget elementor-widget-heading\" data-id=\"2556b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Od 5 klient\u016f\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-47e54af\" data-id=\"47e54af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-93c9579 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93c9579\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-215613e\" data-id=\"215613e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1778c14 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"1778c14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea4e05b\" data-id=\"ea4e05b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeebbe2 elementor-widget elementor-widget-heading\" data-id=\"eeebbe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12\/5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e17d3bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e17d3bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a65a4e\" data-id=\"7a65a4e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcb5ee4 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"bcb5ee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a7d7b6c\" data-id=\"a7d7b6c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2f8457 elementor-widget elementor-widget-heading\" data-id=\"a2f8457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b909357 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b909357\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1a51780\" data-id=\"1a51780\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad2bc61 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ad2bc61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a850a03\" data-id=\"a850a03\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43e0828 elementor-widget elementor-widget-heading\" data-id=\"43e0828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf54fa4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf54fa4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d0081a\" data-id=\"5d0081a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02a1c52 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"02a1c52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8b3ecfa\" data-id=\"8b3ecfa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-708f1df elementor-widget elementor-widget-heading\" data-id=\"708f1df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> 25 % ze zisku\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9442\" aria-expanded=\"false\">Basic 3000\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9442\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9442\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"914\" class=\"elementor elementor-914 elementor-585\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-439159e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"439159e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fabc04a\" data-id=\"fabc04a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-243d393 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"243d393\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6944e3\" data-id=\"c6944e3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca04305 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ca04305\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11b7523\" data-id=\"11b7523\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f354945 elementor-widget elementor-widget-heading\" data-id=\"f354945\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 : 50<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-061b1dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"061b1dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-faf0ee1\" data-id=\"faf0ee1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a7500e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"8a7500e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5912425\" data-id=\"5912425\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db38fc1 elementor-widget elementor-widget-heading\" data-id=\"db38fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.6 Body\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1223fb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1223fb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30e761f\" data-id=\"30e761f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54de8ee elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"54de8ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4eb38e5\" data-id=\"4eb38e5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b938cd4 elementor-widget elementor-widget-heading\" data-id=\"b938cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">21  Dny<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9eaa4cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9eaa4cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eeac719\" data-id=\"eeac719\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-269702a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"269702a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0783999\" data-id=\"0783999\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea079f9 elementor-widget elementor-widget-heading\" data-id=\"ea079f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c2c65e\" data-id=\"1c2c65e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-72c2150 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72c2150\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-629ba41\" data-id=\"629ba41\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90ee730 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"90ee730\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f225c80\" data-id=\"f225c80\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf12495 elementor-widget elementor-widget-heading\" data-id=\"cf12495\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u011bnov\u00e9 p\u00e1ry, komodity, suroviny\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b078cf1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b078cf1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9a5085c\" data-id=\"9a5085c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0481b3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b0481b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c80307c\" data-id=\"c80307c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd7d710 elementor-widget elementor-widget-heading\" data-id=\"fd7d710\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">10%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3f760c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f760c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5734692\" data-id=\"5734692\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cef4be elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"9cef4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-28c1c3c\" data-id=\"28c1c3c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1b038e elementor-widget elementor-widget-heading\" data-id=\"c1b038e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0a32cfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a32cfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d2109a3\" data-id=\"d2109a3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb79162 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"cb79162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d7bf719\" data-id=\"d7bf719\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b0813 elementor-widget elementor-widget-heading\" data-id=\"34b0813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 klient\u016f\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-12d291e\" data-id=\"12d291e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b1c0192 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1c0192\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bfeaca3\" data-id=\"bfeaca3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3f6cff elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"f3f6cff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cb9cea\" data-id=\"1cb9cea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-778d473 elementor-widget elementor-widget-heading\" data-id=\"778d473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12\/5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0cf4db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0cf4db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c2ae420\" data-id=\"c2ae420\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df288b5 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"df288b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b595695\" data-id=\"b595695\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edde370 elementor-widget elementor-widget-heading\" data-id=\"edde370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">20<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c6a6a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c6a6a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0807c35\" data-id=\"0807c35\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40dd760 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"40dd760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a9fa45c\" data-id=\"a9fa45c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-820ebad elementor-widget elementor-widget-heading\" data-id=\"820ebad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9dbba76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dbba76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-acd6876\" data-id=\"acd6876\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b339d50 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b339d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ebb3f1e\" data-id=\"ebb3f1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-918c139 elementor-widget elementor-widget-heading\" data-id=\"918c139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> 25 % ze zisku\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9443\" aria-expanded=\"false\">Standard 10 000\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9443\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9443\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"917\" class=\"elementor elementor-917 elementor-588\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69084a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69084a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-750554c\" data-id=\"750554c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eefc09e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eefc09e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6665e9f\" data-id=\"6665e9f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15b1eb3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"15b1eb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a218fba\" data-id=\"a218fba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc17429 elementor-widget elementor-widget-heading\" data-id=\"fc17429\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 : 50<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b8eb42 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b8eb42\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e7ba88a\" data-id=\"e7ba88a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9312d67 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"9312d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11e78cc\" data-id=\"11e78cc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6c20c6 elementor-widget elementor-widget-heading\" data-id=\"b6c20c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.4 Body\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b97c6a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b97c6a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89572b0\" data-id=\"89572b0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14120e4 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"14120e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-39a6cf4\" data-id=\"39a6cf4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-779a88b elementor-widget elementor-widget-heading\" data-id=\"779a88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 M\u011bs\u00edc\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-96e4f5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96e4f5b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-888b7ed\" data-id=\"888b7ed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4bd04 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3e4bd04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-780c579\" data-id=\"780c579\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-649f204 elementor-widget elementor-widget-heading\" data-id=\"649f204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a8c8996\" data-id=\"a8c8996\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7504a37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7504a37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea2ba46\" data-id=\"ea2ba46\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1615cf elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e1615cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec2db1c\" data-id=\"ec2db1c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65876ed elementor-widget elementor-widget-heading\" data-id=\"65876ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u011bnov\u00e9 p\u00e1ry, komodity, suroviny, akcie, kryptom\u011bny \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cbd4b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cbd4b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aacc7fe\" data-id=\"aacc7fe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-658931e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"658931e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ab319c\" data-id=\"2ab319c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cbf3c6 elementor-widget elementor-widget-heading\" data-id=\"7cbf3c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a51407e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a51407e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e41af27\" data-id=\"e41af27\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba6d6ff elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ba6d6ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-180a268\" data-id=\"180a268\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bdd21b elementor-widget elementor-widget-heading\" data-id=\"7bdd21b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b592cda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b592cda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-78a8d56\" data-id=\"78a8d56\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fb9116 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7fb9116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8239cfc\" data-id=\"8239cfc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df26b32 elementor-widget elementor-widget-heading\" data-id=\"df26b32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 klient\u016f\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c119953\" data-id=\"c119953\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-866df13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"866df13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d07021\" data-id=\"4d07021\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2751cbd elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2751cbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-096ea6c\" data-id=\"096ea6c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8686295 elementor-widget elementor-widget-heading\" data-id=\"8686295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12\/5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-de0754a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de0754a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b92a95c\" data-id=\"b92a95c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-038fcec elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"038fcec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5fbb11c\" data-id=\"5fbb11c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbbabb0 elementor-widget elementor-widget-heading\" data-id=\"dbbabb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Permanentn\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e3fe5ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3fe5ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b00f8a\" data-id=\"6b00f8a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c29496 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3c29496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7b060c5\" data-id=\"7b060c5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a54747 elementor-widget elementor-widget-heading\" data-id=\"7a54747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb13179 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb13179\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-73d2fb8\" data-id=\"73d2fb8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b295b8 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7b295b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3418bc7\" data-id=\"3418bc7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a52fee elementor-widget elementor-widget-heading\" data-id=\"3a52fee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">30% ze zisku\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9444\" aria-expanded=\"false\">Standard+ 25 000\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9444\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9444\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"921\" class=\"elementor elementor-921 elementor-591\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99b652e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99b652e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-600c722\" data-id=\"600c722\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e25f4c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e25f4c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9bd8fc3\" data-id=\"9bd8fc3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7372b81 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7372b81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58484b6\" data-id=\"58484b6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6021fb elementor-widget elementor-widget-heading\" data-id=\"f6021fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 : 150<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f71af2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f71af2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c0d9158\" data-id=\"c0d9158\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7712f2 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"a7712f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2041508\" data-id=\"2041508\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f0b939 elementor-widget elementor-widget-heading\" data-id=\"4f0b939\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.2 Body\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1e799ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e799ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7821605\" data-id=\"7821605\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d1d2af elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"1d1d2af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0b32b0d\" data-id=\"0b32b0d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcdda35 elementor-widget elementor-widget-heading\" data-id=\"bcdda35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3  M\u011bs\u00edc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c2cc12e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2cc12e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-812145f\" data-id=\"812145f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6aebf0 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"c6aebf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3aa00cf\" data-id=\"3aa00cf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5ae2e1 elementor-widget elementor-widget-heading\" data-id=\"f5ae2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e42ce25\" data-id=\"e42ce25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b04f334 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b04f334\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9fad0f9\" data-id=\"9fad0f9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b852892 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b852892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7cd5c8b\" data-id=\"7cd5c8b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e670d44 elementor-widget elementor-widget-heading\" data-id=\"e670d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u011bnov\u00e9 p\u00e1ry, komodity, suroviny, akcie, kryptom\u011bny, indexy \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ccd876 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ccd876\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aae8f8c\" data-id=\"aae8f8c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eff9ded elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"eff9ded\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-883f7b9\" data-id=\"883f7b9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30ed06a elementor-widget elementor-widget-heading\" data-id=\"30ed06a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15+%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0c3bad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0c3bad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-141da7e\" data-id=\"141da7e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46e12f0 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"46e12f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ecff5f7\" data-id=\"ecff5f7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-258bb31 elementor-widget elementor-widget-heading\" data-id=\"258bb31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c78da21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c78da21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-95dee4e\" data-id=\"95dee4e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aab22d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3aab22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2d3f1f9\" data-id=\"2d3f1f9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-101ab2e elementor-widget elementor-widget-heading\" data-id=\"101ab2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Program Cashback\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8f34ab6\" data-id=\"8f34ab6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a0d7347 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0d7347\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e9da40\" data-id=\"2e9da40\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dcd79a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5dcd79a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a01bcfa\" data-id=\"a01bcfa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9de5c4c elementor-widget elementor-widget-heading\" data-id=\"9de5c4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">24\/5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1b9653 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1b9653\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09db506\" data-id=\"09db506\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fb78c4 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"8fb78c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a787e04\" data-id=\"a787e04\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a81b190 elementor-widget elementor-widget-heading\" data-id=\"a81b190\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Permanentn\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14c32a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14c32a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9bfdea4\" data-id=\"9bfdea4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2208995 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2208995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc565cc\" data-id=\"dc565cc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8132fef elementor-widget elementor-widget-heading\" data-id=\"8132fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-beb44dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"beb44dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b2b4151\" data-id=\"b2b4151\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a3dd8a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5a3dd8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d0bac47\" data-id=\"d0bac47\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f37d00 elementor-widget elementor-widget-heading\" data-id=\"8f37d00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">50% ze zisku\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9445\" aria-expanded=\"false\">Advanced 50 000\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9445\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9445\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"924\" class=\"elementor elementor-924 elementor-594\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-390bac1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"390bac1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8c217a6\" data-id=\"8c217a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ddcd6cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddcd6cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b2f6e1\" data-id=\"5b2f6e1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbecb4f elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"fbecb4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3848553\" data-id=\"3848553\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c1625b elementor-widget elementor-widget-heading\" data-id=\"1c1625b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 : 200<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f08935a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f08935a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c116b2\" data-id=\"7c116b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01d3d91 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"01d3d91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-94a2cdd\" data-id=\"94a2cdd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc0c525 elementor-widget elementor-widget-heading\" data-id=\"bc0c525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.2 Body\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7998f2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7998f2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c15f600\" data-id=\"c15f600\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7692479 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7692479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9939c45\" data-id=\"9939c45\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4658f15 elementor-widget elementor-widget-heading\" data-id=\"4658f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">9 M\u011bs\u00edc\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d228d21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d228d21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4416afa\" data-id=\"4416afa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-964fc00 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"964fc00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-89c224b\" data-id=\"89c224b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2126fb elementor-widget elementor-widget-heading\" data-id=\"c2126fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 M\u011bs\u00edc\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-365af0f\" data-id=\"365af0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-15393bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15393bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-31171e2\" data-id=\"31171e2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9303f16 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"9303f16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e075b7\" data-id=\"1e075b7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ba809 elementor-widget elementor-widget-heading\" data-id=\"c5ba809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u011bnov\u00e9 p\u00e1ry, komodity, suroviny, akcie, kryptom\u011bny, indexy \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8375aeb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8375aeb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b22f55e\" data-id=\"b22f55e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aac03f3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"aac03f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e4db85f\" data-id=\"e4db85f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52432c3 elementor-widget elementor-widget-heading\" data-id=\"52432c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15+%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-636a63a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"636a63a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-18cffc5\" data-id=\"18cffc5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e31ace elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"0e31ace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7773bac\" data-id=\"7773bac\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e01f173 elementor-widget elementor-widget-heading\" data-id=\"e01f173\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-718a07c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"718a07c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c49ccea\" data-id=\"c49ccea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fb08a5 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"9fb08a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c9713d8\" data-id=\"c9713d8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f280cd3 elementor-widget elementor-widget-heading\" data-id=\"f280cd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Program Cashback\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d35d13d\" data-id=\"d35d13d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-126d266 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"126d266\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-193a2db\" data-id=\"193a2db\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbb045a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"dbb045a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf20ea1\" data-id=\"cf20ea1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-249ee06 elementor-widget elementor-widget-heading\" data-id=\"249ee06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">24\/5<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd0e6e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd0e6e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f3a15c\" data-id=\"3f3a15c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-214943c elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"214943c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d70d919\" data-id=\"d70d919\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f16f9a0 elementor-widget elementor-widget-heading\" data-id=\"f16f9a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Permanentn\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0347344 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0347344\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c12c7a6\" data-id=\"c12c7a6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35b9ebe elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"35b9ebe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-93d74cc\" data-id=\"93d74cc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c574b2c elementor-widget elementor-widget-heading\" data-id=\"c574b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-341c38c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"341c38c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ca74307\" data-id=\"ca74307\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f5033a elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2f5033a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a0ab228\" data-id=\"a0ab228\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac5bda4 elementor-widget elementor-widget-heading\" data-id=\"ac5bda4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bez omezen\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9446\" aria-expanded=\"false\">Pro Account 100 000\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9446\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9446\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"928\" class=\"elementor elementor-928 elementor-597\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06d6921 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06d6921\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e70772a\" data-id=\"e70772a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac5d909 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac5d909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a7a52dd\" data-id=\"a7a52dd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3aa3126 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3aa3126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b0429e5\" data-id=\"b0429e5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88a5860 elementor-widget elementor-widget-heading\" data-id=\"88a5860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1 : 200<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac37d72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac37d72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3203762\" data-id=\"3203762\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9949a20 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"9949a20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fddda4a\" data-id=\"fddda4a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a955cf elementor-widget elementor-widget-heading\" data-id=\"1a955cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.2 Body\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b4791b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b4791b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-af4c751\" data-id=\"af4c751\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e0a301 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"9e0a301\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5456cec\" data-id=\"5456cec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-974376b elementor-widget elementor-widget-heading\" data-id=\"974376b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">36 M\u011bs\u00edc\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-af05fed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af05fed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9e36bb4\" data-id=\"9e36bb4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c5288d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5c5288d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1eac95b\" data-id=\"1eac95b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1522baa elementor-widget elementor-widget-heading\" data-id=\"1522baa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6 M\u011bs\u00edc\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9a8f092\" data-id=\"9a8f092\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e3eef6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e3eef6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e3dad48\" data-id=\"e3dad48\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2034bdf elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2034bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-34b175e\" data-id=\"34b175e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e16aafe elementor-widget elementor-widget-heading\" data-id=\"e16aafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V\u0161echna aktiva\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35ad41c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35ad41c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09cce1b\" data-id=\"09cce1b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ecc248 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"7ecc248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e6612d2\" data-id=\"e6612d2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d30db0 elementor-widget elementor-widget-heading\" data-id=\"1d30db0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15-25%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e61afc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e61afc3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-697b0b2\" data-id=\"697b0b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f389daf elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"f389daf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-98aa7a0\" data-id=\"98aa7a0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-568a847 elementor-widget elementor-widget-heading\" data-id=\"568a847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a3f360d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3f360d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-325e178\" data-id=\"325e178\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df3c6e9 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"df3c6e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cccfff1\" data-id=\"cccfff1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6340b4 elementor-widget elementor-widget-heading\" data-id=\"d6340b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Program Cashback\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fe7879c\" data-id=\"fe7879c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-309bda3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"309bda3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba41a2e\" data-id=\"ba41a2e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6680f5d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"6680f5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2b685be\" data-id=\"2b685be\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa21b0 elementor-widget elementor-widget-heading\" data-id=\"caa21b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">24\/7<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34ce8fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34ce8fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1daef1c\" data-id=\"1daef1c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e012a79 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"e012a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b35078\" data-id=\"3b35078\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-023aefb elementor-widget elementor-widget-heading\" data-id=\"023aefb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Permanentn\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12df0a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12df0a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68a974f\" data-id=\"68a974f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6532b1 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"f6532b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8c2bae2\" data-id=\"8c2bae2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d75d135 elementor-widget elementor-widget-heading\" data-id=\"d75d135\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c2075b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2075b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-204db46\" data-id=\"204db46\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-827c48c elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"827c48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b32ce02\" data-id=\"b32ce02\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a70eed elementor-widget elementor-widget-heading\" data-id=\"5a70eed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bez omezen\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"7\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-9447\" aria-expanded=\"false\">Vip 250 000\u20ac<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9447\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-9447\" tabindex=\"0\" hidden=\"hidden\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1542\" class=\"elementor elementor-1542 elementor-1538\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ea1e16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ea1e16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d36fdbf\" data-id=\"d36fdbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca163e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca163e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c55c67b\" data-id=\"c55c67b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-112ff63 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"112ff63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"36\" viewBox=\"0 0 37 36\" fill=\"none\"><path d=\"M31.3569 28.435H33.7789V30.707H3.2199V28.435H5.7919V11.421H4.3569C4.20772 11.421 4.06 11.3916 3.92217 11.3345C3.78435 11.2775 3.65912 11.1938 3.55363 11.0883C3.34059 10.8752 3.2209 10.5863 3.2209 10.285V6.42801C3.22119 6.19466 3.29334 5.96707 3.42752 5.77616C3.56171 5.58525 3.75144 5.4403 3.9709 5.36101L18.1139 0.218013C18.3639 0.128013 18.6369 0.128013 18.8859 0.218013L33.0299 5.36001C33.2494 5.4393 33.4391 5.58425 33.5733 5.77516C33.7075 5.96606 33.7796 6.19366 33.7799 6.42701V10.284C33.7799 10.5853 33.6602 10.8742 33.4472 11.0873C33.2341 11.3003 32.9452 11.42 32.6439 11.42H31.2079V28.435H31.3569ZM5.5919 7.18701L5.4919 7.22301V9.15001H31.5079V7.22301L31.4089 7.18701L18.5519 2.50701L18.5009 2.48901L18.4499 2.50701L5.5919 7.18701ZM21.0719 28.435H21.2219V11.421H15.7779V28.435H21.0699H21.0719ZM8.2129 11.421H8.0629V28.435H13.5069V11.421H8.2129ZM28.7849 28.435H28.9349V11.421H23.4929V28.435H28.7849ZM36.3489 33.578V35.85H0.649902V33.578H36.3489Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tP\u00e1kov\u00fd efekt\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20eccde\" data-id=\"20eccde\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d2d6b5 elementor-widget elementor-widget-heading\" data-id=\"9d2d6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1:5 &#8211; 1:200 \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c380f6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c380f6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4b061a2\" data-id=\"4b061a2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90f12c3 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"90f12c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"34\" viewBox=\"0 0 37 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.923 0.342953C2.423 0.460953 1.693 0.890953 1.338 1.27695C1.10732 1.54924 0.911479 1.84922 0.755 2.16995L0.5 2.70795V16.464L0.755 17.002C1.109 17.749 1.565 18.215 2.297 18.577L2.905 18.877L4.373 18.905L5.842 18.933L6.047 18.728C6.316 18.458 6.319 18.092 6.054 17.828C5.862 17.636 5.825 17.631 4.636 17.631C3.912 17.631 3.28 17.591 3.084 17.533C2.642 17.403 1.975 16.736 1.844 16.293C1.774 16.057 1.747 15.008 1.747 12.613V9.26395H28.777V14.661L28.975 14.859C29.237 15.121 29.605 15.12 29.869 14.856L30.069 14.656L30.047 8.68195L30.024 2.70795L29.769 2.16995C29.415 1.42195 28.959 0.956953 28.227 0.594953L27.619 0.294953L15.427 0.280953C8.243 0.273953 3.107 0.299953 2.923 0.342953ZM27.44 1.63895C27.882 1.76895 28.549 2.43595 28.68 2.87795C28.733 3.05995 28.777 3.41295 28.777 3.66195V4.11595H1.747V3.66195C1.747 3.41295 1.791 3.05995 1.845 2.87795C1.965 2.46795 2.639 1.77095 3.035 1.64595C3.459 1.51195 26.988 1.50595 27.44 1.63895ZM28.777 6.68895V7.97695H1.747V5.40295H28.777V6.68895ZM4.52 10.75C4.324 10.946 4.322 10.96 4.322 12.483C4.322 14.006 4.324 14.02 4.52 14.216L4.717 14.414H9.076L9.273 14.216C9.469 14.02 9.471 14.006 9.471 12.483C9.471 10.96 9.469 10.946 9.273 10.75L9.076 10.552H4.716L4.52 10.75ZM11.6 10.75C11.403 10.946 11.402 10.96 11.402 12.483C11.402 14.006 11.403 14.02 11.599 14.216L11.796 14.414H25.809L26.006 14.216C26.202 14.02 26.204 14.006 26.204 12.483C26.204 10.96 26.202 10.946 26.006 10.75L25.809 10.552H11.796L11.598 10.75H11.6ZM8.184 12.483V13.127H5.608V11.839H8.183V12.483H8.184ZM24.917 12.483V13.127H12.688V11.839H24.916L24.917 12.483ZM5.79 21.03C2.094 24.726 1.747 25.096 1.747 25.338C1.747 25.511 1.815 25.67 1.944 25.8L2.142 25.997H11.4V27.284H2.14L1.943 27.482C1.8813 27.5387 1.83205 27.6077 1.79835 27.6844C1.76466 27.7612 1.74727 27.8441 1.74727 27.928C1.74727 28.0118 1.76466 28.0947 1.79835 28.1715C1.83205 28.2483 1.8813 28.3172 1.943 28.374L2.141 28.571H11.4V29.858H2.14L1.943 30.056C1.8813 30.1127 1.83205 30.1817 1.79835 30.2584C1.76466 30.3352 1.74727 30.4181 1.74727 30.502C1.74727 30.5858 1.76466 30.6687 1.79835 30.7455C1.83205 30.8223 1.8813 30.8912 1.943 30.948L2.141 31.146H11.4V32.433H2.14L1.943 32.63C1.82177 32.7473 1.7511 32.9073 1.746 33.076C1.746 33.233 1.819 33.398 1.943 33.523L2.141 33.72H28.412L32.456 29.677C36.152 25.981 36.499 25.611 36.499 25.369C36.4959 25.1952 36.4257 25.0294 36.303 24.9064C36.1803 24.7833 36.0147 24.7125 35.841 24.709C35.601 24.709 35.236 25.051 31.713 28.571L27.849 32.433H18.479V31.146H28.412L32.456 27.102C36.152 23.406 36.499 23.036 36.499 22.795C36.4959 22.6212 36.4257 22.4554 36.303 22.3324C36.1803 22.2093 36.0147 22.1385 35.841 22.135C35.601 22.135 35.236 22.476 31.713 25.997L27.849 29.858H18.479V28.571H28.412L32.456 24.528C36.152 20.832 36.499 20.462 36.499 20.22C36.4957 20.0464 36.4253 19.8808 36.3027 19.758C36.18 19.6351 36.0146 19.5645 35.841 19.561C35.601 19.561 35.236 19.902 31.713 23.423L27.849 27.284H18.479V25.997H28.412L32.456 21.954C36.152 18.258 36.499 17.888 36.499 17.646C36.4989 17.5597 36.4814 17.4743 36.4476 17.3949C36.4137 17.3155 36.3642 17.2438 36.302 17.184L36.104 16.987H9.834L5.79 21.03ZM17.877 18.596L17.562 18.918H12.301L11.951 19.212C11.423 19.656 10.711 19.959 10.065 20.016L9.51 20.066L8.806 20.763C8.198 21.366 8.102 21.499 8.102 21.733C8.102 22.052 8.367 22.377 8.627 22.377C8.723 22.377 8.867 22.45 8.948 22.54C9.091 22.697 9.09 22.711 8.913 23.027C8.706 23.396 8.732 23.65 9.003 23.903C9.167 24.056 9.283 24.066 10.789 24.066H12.399L12.084 24.388L11.77 24.71H3.96L7.177 21.492L10.394 18.274H18.191L17.877 18.596ZM20.773 21.492L17.555 24.71H13.614L16.831 21.492L20.048 18.274H23.99L20.773 21.492ZM31.07 21.492L27.853 24.71H19.413L19.727 24.388L20.041 24.066H25.933L26.383 23.717C26.977 23.257 27.536 23.025 28.196 22.967L28.736 22.919L29.441 22.221C30.049 21.618 30.145 21.485 30.145 21.251C30.145 20.932 29.88 20.607 29.62 20.607C29.497 20.5934 29.383 20.5358 29.299 20.445C29.156 20.287 29.157 20.273 29.334 19.957C29.541 19.588 29.515 19.334 29.244 19.081C29.078 18.926 28.966 18.918 27.137 18.918H25.205L25.519 18.596L25.833 18.274H34.287L31.07 21.492ZM14.98 21.492L13.695 22.779H10.374L10.279 22.403C10.2235 22.1875 10.1355 21.9818 10.018 21.793C9.798 21.483 9.906 21.383 10.596 21.256C11.177 21.148 12.326 20.632 12.561 20.372C12.706 20.212 12.791 20.205 14.489 20.205H16.266L14.98 21.492ZM27.968 20.582C28.02 20.788 28.138 21.062 28.229 21.192C28.449 21.5 28.342 21.6 27.652 21.731C27.033 21.848 26.199 22.21 25.785 22.541L25.488 22.779H21.338L22.623 21.492L23.908 20.205H27.873L27.968 20.581V20.582ZM17.193 29.215V32.433H12.688V25.997H17.193V29.215Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMinim\u00e1ln\u00ed rozp\u011bt\u00ed\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-509ce31\" data-id=\"509ce31\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8544e3 elementor-widget elementor-widget-heading\" data-id=\"d8544e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.2 pips<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ba2ce46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba2ce46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7ae9fa3\" data-id=\"7ae9fa3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59ffa73 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"59ffa73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"26\" viewBox=\"0 0 37 26\" fill=\"none\"><path d=\"M36.2601 9.11197L32.6781 2.24197C32.4285 1.76657 32.0032 1.40741 31.4927 1.24098C30.9822 1.07456 30.4269 1.11402 29.9451 1.35097L26.4821 3.09097H23.9531L19.0721 0.881968C18.6285 0.672941 18.123 0.636578 17.6541 0.779968L10.4341 2.88497L7.0581 1.18997C6.57552 0.956975 6.02152 0.919711 5.51209 1.08598C5.00266 1.25225 4.57731 1.60915 4.3251 2.08197L0.745098 8.96497C0.614989 9.20449 0.534779 9.4679 0.509311 9.73928C0.483844 10.0107 0.513648 10.2844 0.596923 10.5439C0.680199 10.8035 0.815217 11.0435 0.993825 11.2494C1.17243 11.4553 1.39092 11.6229 1.6361 11.742L5.1731 13.511L13.0941 19.693C13.3151 19.876 13.5751 20.006 13.8541 20.073L22.3311 22.193C22.6722 22.2746 23.0284 22.2678 23.3662 22.1734C23.7039 22.0789 24.0119 21.8997 24.2611 21.653L29.6391 16.273H29.6971L31.9191 13.628L35.3681 11.903C35.6124 11.7792 35.8298 11.6083 36.0078 11.4001C36.1858 11.1919 36.3208 10.9506 36.4051 10.69C36.4869 10.4304 36.5161 10.1572 36.491 9.88627C36.4659 9.61532 36.3881 9.35209 36.2601 9.11197ZM28.8791 14.461L23.1061 10.266C22.954 10.1576 22.7713 10.1007 22.5846 10.1034C22.3979 10.1061 22.217 10.1683 22.0681 10.281L20.1981 11.684C19.5394 12.175 18.7397 12.4402 17.9181 12.4402C17.0965 12.4402 16.2968 12.175 15.6381 11.684L14.8481 11.084C14.8111 11.061 14.7808 11.0286 14.7602 10.9902C14.7397 10.9517 14.7296 10.9085 14.7311 10.865C14.7277 10.8241 14.7339 10.7831 14.7492 10.745C14.7644 10.707 14.7884 10.6731 14.8191 10.646L20.5331 4.91697C20.5919 4.87147 20.6637 4.8459 20.7381 4.84397H26.1601L30.3101 12.794L28.8791 14.461ZM2.2791 10.003C2.26333 9.96546 2.25647 9.92481 2.25908 9.8842C2.26168 9.8436 2.27367 9.80415 2.2941 9.76897L5.8891 2.88597C5.91543 2.83987 5.95383 2.80183 6.00017 2.77593C6.04651 2.75003 6.09904 2.73725 6.1521 2.73897C6.19352 2.7333 6.23552 2.74407 6.2691 2.76897L9.1341 4.18597L5.2611 11.596L2.4251 10.164C2.39024 10.1501 2.359 10.1285 2.33371 10.1007C2.30842 10.073 2.28975 10.0389 2.2791 10.003ZM23.0321 20.41C22.996 20.4448 22.9516 20.4698 22.9031 20.4826C22.8546 20.4954 22.8037 20.4955 22.7551 20.483L14.2781 18.379L14.1761 18.32L6.7511 12.518L10.9021 4.56797L18.1521 2.46297C18.2199 2.44633 18.2912 2.45122 18.3561 2.47697L20.0071 3.22297C19.7388 3.32764 19.495 3.48663 19.2911 3.68997L13.5761 9.40497C13.3666 9.61116 13.2044 9.86034 13.1005 10.1353C12.9967 10.4103 12.9538 10.7045 12.9747 10.9977C12.9956 11.2909 13.0799 11.5761 13.2217 11.8335C13.3635 12.091 13.5595 12.3146 13.7961 12.489L14.5851 13.088C15.5502 13.8002 16.7181 14.1846 17.9176 14.1846C19.1171 14.1846 20.285 13.8002 21.2501 13.088L22.6091 12.065L27.6801 15.762L23.0321 20.41ZM34.7251 10.15C34.7154 10.1885 34.6972 10.2243 34.6717 10.2548C34.6463 10.2852 34.6143 10.3096 34.5781 10.326L31.7431 11.743L27.8701 4.34797L30.7351 2.91597C30.8032 2.88499 30.8805 2.88131 30.9512 2.90568C31.0219 2.93005 31.0806 2.98062 31.1151 3.04697L34.7101 9.92997C34.7307 9.96252 34.7428 9.99967 34.7454 10.0381C34.748 10.0765 34.741 10.1149 34.7251 10.15ZM17.0101 24.633C16.9618 24.8223 16.8526 24.9906 16.6995 25.112C16.5463 25.2334 16.3575 25.3012 16.1621 25.305L15.9431 25.275L11.5441 24.165C11.2298 24.0906 10.9386 23.9402 10.6961 23.727L7.4101 20.862C7.30805 20.7923 7.22189 20.7019 7.15727 20.5966C7.09265 20.4913 7.05104 20.3735 7.03516 20.251C7.01929 20.1284 7.02951 20.004 7.06516 19.8857C7.1008 19.7674 7.16107 19.6579 7.242 19.5646C7.32293 19.4712 7.42269 19.3961 7.53473 19.344C7.64677 19.2919 7.76856 19.2642 7.8921 19.2625C8.01563 19.2608 8.13813 19.2853 8.25153 19.3343C8.36493 19.3834 8.46668 19.4558 8.5501 19.547L11.8531 22.411C11.8871 22.4393 11.9271 22.4595 11.9701 22.47L16.3841 23.566C16.6086 23.6245 16.8008 23.7697 16.9185 23.9697C17.0362 24.1697 17.0699 24.4082 17.0121 24.633H17.0101Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Odborn\u00e1 podpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e88e679\" data-id=\"e88e679\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27482f2 elementor-widget elementor-widget-heading\" data-id=\"27482f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bez omezen\u00ed<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a462e2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a462e2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27eafb4\" data-id=\"27eafb4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3976297 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"3976297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M27.5469 0.752013C25.7619 1.39001 25.6069 3.82901 27.2969 4.66001C27.6309 4.82301 27.7949 4.85801 28.2349 4.85801C29.4709 4.85801 30.3309 3.99801 30.3309 2.75901C30.3309 2.15301 30.1839 1.74801 29.8059 1.31801C29.2959 0.737013 28.2929 0.485013 27.5469 0.752013ZM28.5809 2.14901C28.9189 2.32401 29.0339 2.73901 28.8459 3.10501C28.6009 3.57801 27.8699 3.57801 27.6259 3.10501C27.5494 2.97168 27.5188 2.81684 27.539 2.66441C27.5592 2.51199 27.629 2.37045 27.7377 2.26167C27.8464 2.15289 27.9878 2.08291 28.1403 2.06255C28.2927 2.04219 28.4475 2.07257 28.5809 2.14901ZM15.9909 2.25301C15.6189 2.39901 15.3799 2.55701 13.9249 3.62101C13.5284 3.9158 13.1249 4.20122 12.7149 4.47701C12.5889 4.54901 12.0359 4.58301 10.5189 4.60901L8.49094 4.64501L8.08794 4.84201C7.58794 5.08801 7.15994 5.49601 6.93794 5.94101C6.84494 6.12801 6.54094 6.98601 6.26294 7.84701C5.98394 8.70701 5.70994 9.47801 5.65294 9.55901C5.59494 9.64001 4.92494 10.159 4.16294 10.714C2.64994 11.814 2.27294 12.181 2.05394 12.766C1.78194 13.494 1.83694 13.927 2.44294 15.785C2.73894 16.692 2.97694 17.545 2.97694 17.701C2.97694 17.856 2.73894 18.71 2.44294 19.617C1.83694 21.475 1.78194 21.908 2.05394 22.637C2.27294 23.221 2.64994 23.587 4.16394 24.688C4.92394 25.242 5.59394 25.762 5.65194 25.843C5.70994 25.923 5.99194 26.713 6.27994 27.597C6.56794 28.48 6.87194 29.338 6.95594 29.503C7.16494 29.911 7.60494 30.323 8.08794 30.56L8.49094 30.757L10.5189 30.793C11.9959 30.819 12.5909 30.853 12.7089 30.921C12.7979 30.971 13.4379 31.428 14.1319 31.935C15.7309 33.105 15.9959 33.24 16.7519 33.272C17.5709 33.307 17.8969 33.155 19.4969 31.987C19.9881 31.6225 20.4862 31.2675 20.9909 30.922C21.1119 30.853 21.6919 30.819 23.1839 30.792C25.1829 30.758 25.2169 30.755 25.6029 30.572C26.0529 30.36 26.5459 29.895 26.7549 29.486C26.8339 29.33 27.1349 28.48 27.4219 27.596C27.7099 26.713 27.9939 25.922 28.0529 25.839C28.1129 25.755 28.7709 25.246 29.5179 24.706C31.0159 23.624 31.4279 23.224 31.6469 22.64C31.9209 21.907 31.8659 21.477 31.2589 19.617C30.9629 18.71 30.7259 17.857 30.7259 17.701C30.7259 17.546 30.9629 16.692 31.2589 15.785C31.8659 13.925 31.9209 13.495 31.6469 12.762C31.4289 12.178 31.0159 11.778 29.5179 10.696C28.7709 10.156 28.1119 9.64601 28.0529 9.56301C27.9939 9.48001 27.7099 8.68901 27.4229 7.80501C27.1339 6.92201 26.8299 6.06401 26.7459 5.89901C26.5349 5.48601 26.0689 5.04901 25.6029 4.82901C25.2169 4.64701 25.1829 4.64401 23.1829 4.60901C21.6929 4.58301 21.1129 4.54901 20.9909 4.47901C20.9009 4.42901 20.2289 3.94901 19.4969 3.41601C18.7659 2.88201 17.9909 2.37201 17.7769 2.28401C17.2789 2.07801 16.4729 2.06301 15.9909 2.25301ZM4.40694 2.86001C3.79094 3.20101 4.04894 4.18301 4.75494 4.18301C5.11494 4.18301 5.46694 3.83601 5.46694 3.47901C5.46694 2.94401 4.87694 2.60001 4.40694 2.86001ZM17.4199 3.69401C17.5569 3.77801 18.2399 4.26201 18.9379 4.77001C19.6359 5.28001 20.3719 5.76201 20.5749 5.84401C20.9079 5.97901 21.1309 5.99601 22.9379 6.03101C25.0959 6.07101 25.1619 6.08401 25.4259 6.48801C25.4869 6.58001 25.7889 7.41301 26.0979 8.33801C26.4079 9.26401 26.7249 10.124 26.8029 10.25C27.0279 10.612 27.3949 10.924 28.7929 11.937C29.5329 12.473 30.1579 12.98 30.2349 13.105C30.4599 13.475 30.4049 13.82 29.8359 15.563C29.3769 16.971 29.3029 17.27 29.3029 17.702C29.3029 18.134 29.3769 18.432 29.8359 19.842C30.4049 21.584 30.4599 21.929 30.2349 22.299C30.1579 22.424 29.5329 22.931 28.7939 23.467C27.3949 24.48 27.0279 24.792 26.8029 25.154C26.7239 25.28 26.4069 26.14 26.0979 27.066C25.7889 27.991 25.4869 28.824 25.4259 28.916C25.1619 29.32 25.0959 29.332 22.9379 29.373C21.1309 29.408 20.9079 29.425 20.5749 29.56C20.3719 29.642 19.6359 30.125 18.9379 30.633C17.3109 31.82 17.2419 31.861 16.8509 31.861C16.4629 31.861 16.4159 31.833 14.7789 30.641C14.0749 30.129 13.3339 29.643 13.1299 29.561C12.7939 29.425 12.5749 29.408 10.7639 29.373C8.60594 29.333 8.54094 29.32 8.27594 28.916C8.21594 28.824 7.91294 27.991 7.60394 27.066C7.29394 26.14 6.97794 25.28 6.89894 25.154C6.67094 24.786 6.29694 24.469 4.90894 23.467C4.15894 22.924 3.54794 22.43 3.46894 22.301C3.24394 21.933 3.29894 21.595 3.86594 19.846C4.57594 17.658 4.57594 17.739 3.86594 15.563C3.29594 13.817 3.24194 13.476 3.46894 13.103C3.54794 12.973 4.15894 12.48 4.90894 11.937C6.29694 10.935 6.67094 10.618 6.89894 10.25C6.97794 10.124 7.29494 9.26401 7.60394 8.33801C7.91294 7.41301 8.21494 6.58001 8.27594 6.48801C8.54094 6.08401 8.60594 6.07201 10.7639 6.03101C12.5749 5.99601 12.7939 5.97901 13.1299 5.84301C13.3339 5.76101 14.0749 5.27501 14.7779 4.76301C15.2765 4.39525 15.7819 4.03685 16.2939 3.68801C16.6109 3.49501 17.0959 3.49801 17.4199 3.69401ZM28.5999 6.41601C27.9829 6.75801 28.2409 7.74001 28.9479 7.74001C29.3079 7.74001 29.6589 7.39201 29.6589 7.03501C29.657 6.91171 29.6233 6.79098 29.5611 6.68449C29.4989 6.57801 29.4103 6.48937 29.3038 6.42713C29.1974 6.3649 29.0767 6.33118 28.9534 6.32923C28.83 6.32729 28.7083 6.35717 28.5999 6.41601ZM15.5849 7.81801C14.3399 7.98701 13.0249 8.42801 11.9769 9.02801C11.0589 9.55501 10.4189 10.058 9.65694 10.854C8.32494 12.246 7.50494 13.803 7.09094 15.731C6.86794 16.769 6.86794 18.633 7.09094 19.671C7.38094 21.023 7.85894 22.151 8.64594 23.341C9.08694 24.01 10.5499 25.469 11.2299 25.921C12.3899 26.691 13.6799 27.223 15.0399 27.495C15.9919 27.685 17.8529 27.668 18.8209 27.461C20.1709 27.171 21.2999 26.694 22.4909 25.906C23.1599 25.465 24.6189 24.003 25.0709 23.322C25.8409 22.162 26.3729 20.872 26.6449 19.512C26.8349 18.56 26.8189 16.699 26.6109 15.731C26.1739 13.692 25.3479 12.178 23.8609 10.691C22.3769 9.20601 20.8539 8.37101 18.8579 7.95101C18.0459 7.78101 16.3659 7.71301 15.5849 7.81801ZM18.7009 9.36801C19.9419 9.65372 21.1045 10.2097 22.1058 10.9964C23.1072 11.7831 23.9226 12.781 24.4939 13.919C25.0939 15.109 25.3539 16.254 25.3539 17.701C25.3539 18.821 25.2699 19.377 24.9569 20.345C24.5449 21.617 23.8599 22.723 22.8669 23.72C21.6937 24.9103 20.195 25.7275 18.5589 26.069C17.8039 26.231 16.0569 26.251 15.3209 26.105C12.2169 25.49 9.69694 23.282 8.74494 20.345C8.43194 19.377 8.34894 18.822 8.34894 17.701C8.34894 16.581 8.43194 16.025 8.74494 15.057C9.43694 12.921 11.0209 11.089 13.0689 10.057C13.7939 9.70411 14.5637 9.45178 15.3569 9.30701C15.6499 9.26001 15.9389 9.20901 15.9969 9.19501C16.2949 9.12301 18.1499 9.24101 18.7009 9.36701V9.36801ZM16.6379 11.843C16.3179 11.968 16.2039 12.207 15.6309 13.975L15.0469 15.78H11.1479L10.9399 15.988C10.7209 16.207 10.6599 16.579 10.7999 16.841C10.8379 16.911 11.5429 17.458 12.3669 18.056C13.1919 18.654 13.8789 19.164 13.8959 19.191C13.9119 19.217 13.6709 20.017 13.3599 20.97C13.0499 21.922 12.7959 22.794 12.7959 22.907C12.7959 23.021 12.8459 23.191 12.9079 23.285C13.0399 23.487 13.4399 23.637 13.6579 23.568C13.7429 23.541 14.4959 23.024 15.3319 22.419L16.8509 21.319L17.0819 21.483C17.2089 21.573 17.8919 22.067 18.5979 22.582C19.3039 23.096 19.9529 23.539 20.0399 23.567C20.4359 23.693 20.9069 23.317 20.9069 22.873C20.9069 22.778 20.6529 21.923 20.3419 20.97C20.0319 20.017 19.7909 19.217 19.8069 19.19C19.8239 19.163 20.5099 18.655 21.3319 18.061C22.1549 17.467 22.8599 16.921 22.8989 16.848C22.9674 16.708 22.991 16.5503 22.9665 16.3963C22.942 16.2424 22.8705 16.0998 22.7619 15.988L22.5539 15.78H18.6559L18.0709 13.975C17.6619 12.715 17.4379 12.125 17.3249 12.02C17.1549 11.86 16.8169 11.773 16.6379 11.843ZM17.1919 15.873C17.6039 17.193 17.5609 17.161 18.9599 17.19L20.0619 17.213L19.1869 17.866C18.5179 18.366 18.2969 18.57 18.2509 18.736C18.2029 18.91 18.2559 19.153 18.5139 19.943C18.6929 20.487 18.8309 20.939 18.8219 20.948C18.8119 20.958 18.4249 20.691 17.9619 20.355C16.8399 19.545 16.8519 19.545 15.7409 20.358C15.2809 20.695 14.8949 20.962 14.8839 20.951C14.8729 20.941 15.0089 20.49 15.1859 19.949C15.4139 19.253 15.4939 18.907 15.4619 18.76C15.4119 18.534 15.2179 18.356 14.2649 17.668L13.6359 17.213L14.7399 17.19C16.1419 17.161 16.0979 17.193 16.5099 15.872C16.6729 15.352 16.8259 14.926 16.8509 14.926C16.8759 14.926 17.0299 15.352 17.1919 15.872V15.873ZM2.27194 25.627C1.65594 25.969 1.91394 26.951 2.62094 26.951C2.98094 26.951 3.33194 26.603 3.33194 26.246C3.33194 25.712 2.74194 25.366 2.27194 25.627ZM30.0919 27.784C29.4639 28.006 28.9469 28.754 28.9469 29.441C28.9469 30.379 29.7869 31.22 30.7259 31.22C31.1559 31.22 31.6529 31.008 31.9729 30.688C33.3119 29.349 31.8869 27.15 30.0919 27.784ZM1.93294 28.501C0.14794 29.139 -0.00805962 31.578 1.68294 32.409C1.97592 32.5487 2.29638 32.6211 2.62094 32.6211C2.9455 32.6211 3.26596 32.5487 3.55894 32.409C4.32194 32.034 4.71694 31.386 4.71694 30.509C4.71694 29.902 4.56894 29.497 4.19194 29.067C3.68194 28.486 2.67894 28.235 1.93294 28.501ZM30.9699 29.197C31.0334 29.2635 31.0725 29.3495 31.0809 29.441C31.0723 29.5325 31.0332 29.6184 30.9699 29.685C30.9036 29.7489 30.8176 29.7884 30.7259 29.797C30.6343 29.7883 30.5483 29.7488 30.4819 29.685C30.4182 29.6186 30.3787 29.5327 30.3699 29.441C30.3699 29.368 30.4199 29.259 30.4819 29.197C30.5483 29.1332 30.6343 29.0938 30.7259 29.085C30.7979 29.085 30.9079 29.135 30.9699 29.197ZM2.96594 29.898C3.44594 30.146 3.43194 30.912 2.94294 31.135C2.57794 31.301 2.17994 31.181 2.01094 30.854C1.93436 30.7207 1.90381 30.5658 1.92402 30.4134C1.94422 30.261 2.01405 30.1195 2.12271 30.0107C2.23138 29.9019 2.37284 29.8319 2.52525 29.8116C2.67766 29.7912 2.83253 29.8216 2.96594 29.898ZM25.7529 32.031C25.1359 32.373 25.3939 33.354 26.1009 33.354C26.4609 33.354 26.8119 33.007 26.8119 32.65C26.8119 32.115 26.2219 31.77 25.7519 32.03L25.7529 32.031Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0158\u00edzen\u00ed d\u016fv\u011bry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aa00416\" data-id=\"aa00416\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-702427c elementor-widget elementor-widget-heading\" data-id=\"702427c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">12 M\u011bs\u00edc\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6bf8bd6\" data-id=\"6bf8bd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14c3641 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14c3641\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-220176b\" data-id=\"220176b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a1e777 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"8a1e777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.2668 0.893006C13.2308 1.32901 11.6818 2.73901 10.9198 4.85001C10.6738 5.53101 10.6118 7.18201 10.8038 7.94001C11.2378 9.64901 12.3668 11.07 13.8908 11.825C14.8228 12.286 15.4538 12.425 16.5848 12.419C17.4228 12.414 17.6708 12.379 18.2528 12.181C20.2468 11.502 21.6008 10.069 22.1538 8.05301C22.3078 7.49301 22.3298 7.23001 22.2958 6.35901C22.2518 5.23201 22.0518 4.51901 21.5308 3.63101C20.2708 1.48801 17.7118 0.370006 15.2668 0.893006ZM18.0718 2.23501C19.9398 2.91601 21.1188 4.61001 21.1188 6.61101C21.1188 8.22001 20.4018 9.57301 19.0848 10.448C17.6328 11.412 15.9768 11.515 14.4248 10.738C12.8198 9.93501 11.8808 8.41201 11.8808 6.61101C11.8808 4.36101 13.3808 2.51401 15.6008 2.03101C16.2108 1.89901 17.4238 1.99901 18.0718 2.23501ZM16.0868 3.51601C15.9848 3.62501 15.8998 3.80801 15.8988 3.92201C15.8968 4.08201 15.8148 4.16801 15.5518 4.29001C14.6918 4.68601 14.4368 5.90401 15.0618 6.61801C15.4318 7.03801 15.7268 7.16801 16.3188 7.16801C16.8638 7.16801 17.0988 7.29801 17.0988 7.59801C17.0988 7.85101 16.8288 7.93801 16.0348 7.93801C15.4158 7.93801 15.2748 7.96401 15.1308 8.10801C14.7708 8.46801 15.0088 9.01401 15.5638 9.10301C15.8378 9.14601 15.9008 9.19201 15.9008 9.34401C15.9008 9.59201 16.2408 9.90401 16.5118 9.90401C16.7798 9.90401 17.0988 9.57601 17.0988 9.30001C17.0988 9.14201 17.1868 9.04501 17.4618 8.89801C18.3348 8.43401 18.5648 7.32101 17.9368 6.60501C17.5698 6.18701 17.2518 6.04401 16.5488 5.98101C16.0008 5.93201 15.9408 5.90801 15.9158 5.73001C15.8638 5.36001 16.0278 5.28601 16.8958 5.28601C17.5838 5.28601 17.7218 5.26101 17.8688 5.11401C18.2508 4.73201 17.9208 4.08801 17.3438 4.08801C17.1438 4.08801 17.0988 4.05101 17.0988 3.88901C17.0988 3.63201 16.7628 3.31901 16.4878 3.31901C16.3698 3.31901 16.1878 3.40701 16.0868 3.51601ZM3.75483 13.65C3.36083 13.775 3.32783 13.894 3.32783 15.178V16.405H2.10183C0.328829 16.405 0.504829 15.945 0.504829 20.585V24.368L0.714829 24.578C0.917829 24.781 0.964829 24.788 2.12583 24.788H3.32783V26.015C3.32783 27.38 3.38183 27.525 3.89783 27.525C4.39383 27.525 4.47783 27.311 4.50983 25.977L4.53783 24.787H5.67483C6.69483 24.787 6.83483 24.77 7.03683 24.61L7.26183 24.433V16.754L7.07483 16.58C6.90483 16.422 6.77683 16.405 5.70583 16.405H4.52483V15.297C4.52483 14.651 4.48483 14.1 4.42783 13.976C4.32483 13.751 3.97283 13.581 3.75483 13.65ZM20.5418 13.65C20.1618 13.71 20.0918 13.956 20.0918 15.227V16.405H18.9138C17.9858 16.405 17.6948 16.433 17.5448 16.538L17.3548 16.672V20.559C17.3548 24.331 17.3598 24.451 17.5258 24.617C17.6808 24.771 17.8108 24.787 18.8948 24.787H20.0928V25.985C20.0928 27.069 20.1088 27.199 20.2628 27.354C20.3912 27.4673 20.5576 27.528 20.7288 27.524C21.2208 27.524 21.2898 27.333 21.2898 25.966V24.788H22.4908C23.6528 24.788 23.6998 24.781 23.9028 24.578L24.1128 24.368V16.826L23.9028 16.616C23.6998 16.412 23.6528 16.406 22.4908 16.406H21.2898V15.226C21.2898 13.784 21.1788 13.55 20.5418 13.65ZM6.06483 20.596V23.59H1.70283V17.603H6.06483V20.596ZM22.9148 20.596V23.59H18.5528V17.603H22.9148V20.596ZM11.8808 19.485C11.7258 19.639 11.7098 19.77 11.7098 20.853V22.051H10.5218C9.47983 22.051 9.30883 22.071 9.13183 22.214L8.92983 22.378L8.90583 26.177C8.88283 29.926 8.88483 29.979 9.06183 30.204L9.24183 30.434H11.7098V31.66C11.7098 32.781 11.7248 32.9 11.8818 33.043C12.1258 33.263 12.5548 33.244 12.7498 33.003C12.8858 32.836 12.9078 32.648 12.9078 31.621V30.433H14.0858C15.0138 30.433 15.3048 30.405 15.4538 30.3L15.6438 30.167V26.3C15.6428 24.174 15.6138 22.392 15.5788 22.34C15.4258 22.11 15.0988 22.05 14.0248 22.05H12.9078V20.932C12.9078 19.564 12.8128 19.317 12.2878 19.314C12.1366 19.3222 11.9929 19.3822 11.8808 19.484V19.485ZM28.6808 19.493C28.5408 19.648 28.5138 19.837 28.4898 20.862L28.4618 22.051H27.3248C26.3048 22.051 26.1648 22.069 25.9628 22.228L25.7378 22.405V26.248C25.7378 29.977 25.7428 30.096 25.9078 30.262C26.0638 30.417 26.1938 30.433 27.2778 30.433H28.4748V31.541C28.4748 32.77 28.5428 33.021 28.9188 33.177C29.1368 33.267 29.2008 33.258 29.3998 33.11C29.6288 32.939 29.6298 32.933 29.6528 31.686L29.6768 30.433H30.8998C32.6698 30.433 32.4948 30.893 32.4948 26.253V22.47L32.2848 22.26C32.0818 22.057 32.0348 22.05 30.8738 22.05H29.6728V20.823C29.6728 19.743 29.6528 19.58 29.5158 19.455C29.2958 19.256 28.8778 19.275 28.6808 19.493ZM14.4468 26.242V29.236H10.0848V23.248H14.4468V26.242ZM31.2968 26.242V29.236H26.9348V23.248H31.2978L31.2968 26.242Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAktiva\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-81410e5\" data-id=\"81410e5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a55f915 elementor-widget elementor-widget-heading\" data-id=\"a55f915\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V\u0161echna aktiva\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9250c36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9250c36\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63ca16a\" data-id=\"63ca16a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba153a9 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ba153a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.02811 0.189961C0.940114 0.208961 0.788114 0.319961 0.688114 0.438961C0.428114 0.746961 0.438114 1.13996 0.715114 1.44896L0.924114 1.68396L2.18411 1.70696L3.44411 1.73096L3.46411 17.535L3.48211 33.338L3.68911 33.555C3.94111 33.818 4.21711 33.888 4.50711 33.764C4.62711 33.712 5.54011 32.944 6.53611 32.057C7.53311 31.169 8.39111 30.417 8.44511 30.385C8.51311 30.343 9.04511 30.815 10.2641 31.998C11.2381 32.944 12.0881 33.712 12.2221 33.765C12.4181 33.844 12.4971 33.844 12.6821 33.765C12.8051 33.713 13.6901 32.943 14.6491 32.053C15.6071 31.164 16.4351 30.41 16.4871 30.378C16.5561 30.336 17.0881 30.82 18.3171 32.04C20.1301 33.841 20.2651 33.941 20.6871 33.78C20.7951 33.74 21.6701 32.948 22.6321 32.02C23.5931 31.094 24.4121 30.335 24.4511 30.335C24.4901 30.335 25.3931 31.107 26.4571 32.05C27.7521 33.197 28.4641 33.78 28.6111 33.812C28.8811 33.872 29.1631 33.742 29.3661 33.468L29.5161 33.265L29.5341 17.498L29.5531 1.73096L30.8131 1.70696L32.0731 1.68396L32.2831 1.44896C32.5731 1.12596 32.5731 0.735961 32.2831 0.411961L32.0731 0.177961L16.6301 0.167961C8.13611 0.162961 1.11511 0.173961 1.02811 0.190961V0.189961ZM27.9741 16.543V31.368L27.7051 31.115C27.1941 30.634 24.9971 28.712 24.8201 28.591C24.6966 28.5166 24.5562 28.475 24.4121 28.47C24.1351 28.47 23.8821 28.685 21.8431 30.652L20.4361 32.009L18.7011 30.283C17.7461 29.333 16.8901 28.535 16.7971 28.507C16.3891 28.383 16.2241 28.501 14.3221 30.266L12.4691 31.986L10.6891 30.26C8.80911 28.437 8.65211 28.327 8.25311 28.54C8.11611 28.614 5.95911 30.49 5.25711 31.148L5.02411 31.367V1.71896H27.9741V16.543ZM19.0901 4.92796C18.9751 5.02496 14.7781 11.778 12.9881 14.745C12.6191 15.357 12.5981 15.688 12.9061 15.996C13.1941 16.284 13.6081 16.289 13.9131 16.009C14.0311 15.9 15.5161 13.552 17.2131 10.791C20.6191 5.25096 20.5231 5.44496 20.0891 5.01196C19.9201 4.84296 19.8181 4.80196 19.5591 4.80196C19.3591 4.80196 19.1841 4.84896 19.0901 4.92796ZM11.3231 5.68796C10.5761 5.96596 10.0151 6.47396 9.69611 7.16096C9.54111 7.49396 9.50811 7.66896 9.50611 8.17496C9.50611 8.72096 9.53011 8.83596 9.73811 9.25896C10.0121 9.81842 10.47 10.2668 11.0351 10.529C11.3811 10.691 11.5381 10.719 12.0871 10.719C12.6371 10.719 12.7931 10.691 13.1411 10.528C13.6899 10.2562 14.1343 9.81174 14.4061 9.26296C14.5741 8.90496 14.5971 8.76596 14.5961 8.13696C14.5961 7.49196 14.5761 7.38196 14.3951 7.03696C14.1251 6.52296 13.6371 6.04996 13.1411 5.82296C12.6481 5.59696 11.7451 5.52896 11.3231 5.68696V5.68796ZM12.5511 7.25796C12.9591 7.46796 13.1461 7.80296 13.1071 8.25396C13.0876 8.44887 13.0243 8.63686 12.9221 8.80396C12.7251 9.08096 12.2201 9.28396 11.8821 9.21996C10.9151 9.03796 10.7371 7.66796 11.6221 7.22296C11.9541 7.05596 12.1721 7.06396 12.5511 7.25796ZM20.0841 10.362C19.3911 10.59 18.6821 11.312 18.4701 12.005C18.3141 12.517 18.3321 13.25 18.5121 13.731C18.7231 14.296 19.3071 14.907 19.8841 15.169C20.2481 15.334 20.4381 15.374 20.8731 15.376C22.1381 15.382 23.1111 14.632 23.4241 13.409C23.7191 12.259 23.1341 11.029 22.0321 10.489C21.6981 10.325 21.5171 10.286 21.0161 10.273C20.6301 10.263 20.2891 10.294 20.0841 10.362ZM21.4471 11.921C21.8171 12.172 21.9611 12.413 21.9611 12.781C21.9611 13.44 21.5591 13.838 20.8961 13.839C20.4801 13.839 20.1711 13.642 19.9661 13.245C19.8241 12.97 19.8711 12.461 20.0631 12.199C20.3801 11.766 21.0291 11.636 21.4471 11.921ZM8.45411 19.413C8.35895 19.4739 8.27851 19.5552 8.21861 19.651C8.1587 19.7468 8.12082 19.8548 8.10772 19.967C8.09461 20.0792 8.10659 20.193 8.1428 20.3C8.17902 20.4071 8.23856 20.5047 8.31711 20.586L8.52711 20.796H24.4711L24.6811 20.586C24.9111 20.355 24.9581 20.019 24.8041 19.682C24.6171 19.272 25.0021 19.29 16.4841 19.292C9.31011 19.293 8.62911 19.305 8.45411 19.413ZM8.56511 23.193C8.42729 23.2462 8.30935 23.3409 8.22752 23.4639C8.14568 23.5869 8.10397 23.7323 8.10811 23.88C8.10811 24.2 8.27311 24.44 8.58111 24.569C8.93911 24.719 17.9671 24.717 18.3251 24.567C18.5781 24.461 18.7941 24.144 18.7941 23.88C18.7941 23.615 18.5781 23.298 18.3251 23.193C17.9721 23.045 8.90511 23.046 8.56511 23.193Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOdborn\u00e1 komise\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a7a7d0f\" data-id=\"a7a7d0f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f307bfd elementor-widget elementor-widget-heading\" data-id=\"f307bfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">15-25%<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-027e2aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"027e2aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7970af1\" data-id=\"7970af1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93a009d elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"93a009d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"28\" viewBox=\"0 0 33 28\" fill=\"none\"><path d=\"M15.6472 2.63901L15.5792 2.56501C15.6153 2.53656 15.6558 2.51427 15.6992 2.49901C15.7492 2.47801 15.8182 2.45401 15.9052 2.42501C16.0792 2.36801 16.3352 2.29301 16.6902 2.19501C17.4002 2.00001 18.5112 1.71001 20.1702 1.28701C21.5489 0.935427 22.9289 0.588758 24.3102 0.247012C24.4323 0.217773 24.5546 0.189439 24.6772 0.162012C24.6943 0.158198 24.7117 0.155526 24.7292 0.154012C24.7325 0.153767 24.7358 0.153433 24.7392 0.153012L24.7512 0.152012C24.7612 0.152012 24.7762 0.150012 24.7932 0.152012C24.8318 0.157 24.8691 0.169213 24.9032 0.188012C24.9812 0.227012 25.1112 0.311012 25.3632 0.488012C25.8272 0.815012 26.7262 1.47201 28.5212 2.78301L29.0342 3.15801C29.9112 3.79801 30.7272 4.40101 31.3362 4.85701C31.6585 5.09834 31.9789 5.34235 32.2972 5.58901C32.3356 5.6186 32.3723 5.65032 32.4072 5.68401L32.3342 5.75201C32.5432 5.97601 32.5542 6.18801 32.3662 6.39701C32.2492 6.52601 31.9762 6.61701 30.7902 6.92001L15.6472 2.64001V2.63901ZM15.6472 2.63901L15.5792 2.56501C15.4807 2.66395 15.4207 2.79481 15.4102 2.93401C15.3919 3.07084 15.4262 3.2095 15.5062 3.32201C15.5223 3.34049 15.5401 3.35755 15.5592 3.37301C15.679 3.47088 15.8003 3.56689 15.9232 3.66101C16.1512 3.83401 16.4532 4.06001 16.7762 4.29501C17.1513 4.5697 17.5249 4.84637 17.8972 5.12501M15.6472 2.63901C15.4902 2.78401 15.4582 3.09901 15.5852 3.26001C15.6282 3.31401 16.1892 3.74401 16.8342 4.21501C17.4782 4.68501 18.0072 5.07701 18.0072 5.08501C18.0072 5.09301 17.8942 5.65901 17.7572 6.34101C17.6192 7.02401 17.5072 7.71701 17.5072 7.88101C17.5072 9.22301 19.5182 10.996 21.7882 11.654C23.0862 12.03 24.7362 12.094 25.9482 11.818C27.4062 11.485 28.5452 10.755 28.7912 9.99801M28.8862 10.028C28.9287 9.86409 28.9667 9.69903 29.0002 9.53301C29.0552 9.27301 29.1252 8.93501 29.1962 8.58301L29.4412 7.36801L28.7912 9.99801M28.8862 10.028L28.7912 9.99801ZM28.8862 10.028L28.7912 9.99801ZM28.8862 10.028C28.7532 10.439 28.3842 10.827 27.8782 11.151C27.3692 11.477 26.7082 11.747 25.9712 11.915C24.7412 12.197 23.0732 12.13 21.7612 11.75C20.6448 11.4229 19.6116 10.8602 18.7312 10.1C17.9382 9.40001 17.4072 8.59701 17.4072 7.88101C17.4072 7.78901 17.4372 7.56601 17.4812 7.29001C17.5272 7.01001 17.5902 6.66401 17.6592 6.32101C17.7363 5.93745 17.813 5.55378 17.8892 5.17001L17.8972 5.12501M17.8972 5.12501C17.9103 5.13484 17.9233 5.14484 17.9362 5.15501C17.9372 5.15601 17.9362 5.15601 17.9362 5.15501L17.9292 5.14801C17.9258 5.14392 17.9228 5.13957 17.9202 5.13501C17.9114 5.11983 17.9069 5.10255 17.9072 5.08501V5.07501L17.9032 5.09501L17.8972 5.12501ZM3.43715 24.648L3.42115 16.834L3.40415 8.91901V8.89701L3.41415 8.87701L3.56315 8.55001C3.73315 8.18101 4.06015 7.86901 4.42415 7.73701L3.43715 24.648ZM3.43715 24.648H0.771153L0.742153 24.678L0.589153 24.831C0.457153 24.962 0.404153 25.159 0.400153 25.371C0.396153 25.584 0.440153 25.828 0.522153 26.074C0.684153 26.564 0.999153 27.081 1.39715 27.396C1.42815 27.42 1.45715 27.446 1.48415 27.472C1.57744 27.5691 1.69473 27.6398 1.82415 27.677C2.04815 27.744 2.44415 27.783 3.27615 27.807C4.71615 27.85 7.50115 27.85 13.0662 27.849H16.0062C21.9412 27.849 25.3522 27.845 27.3142 27.832C28.2942 27.826 28.9142 27.817 29.3052 27.804C29.451 27.8002 29.5967 27.7928 29.7422 27.782C29.8129 27.7787 29.8833 27.7686 29.9522 27.752L29.9232 27.655L29.9522 27.751C30.8422 27.487 31.5002 26.564 31.5892 25.497C31.6052 25.309 31.6132 25.184 31.5922 25.089C31.5692 24.981 31.5102 24.916 31.4332 24.839L31.2712 24.677L31.2412 24.648H28.5762L28.5932 18.653L28.6102 12.557V12.516L28.5802 12.486L28.4262 12.332C28.3721 12.2754 28.3072 12.23 28.2355 12.1986C28.1637 12.1672 28.0865 12.1503 28.0082 12.149C27.93 12.1499 27.8527 12.1664 27.7809 12.1975C27.7092 12.2285 27.6443 12.2736 27.5902 12.33L27.4362 12.484L27.4072 12.514V24.4L27.2832 24.524L27.1592 24.648H4.85415L4.73015 24.524L4.60615 24.4V9.06301L4.71915 8.95601L4.83515 8.84801H10.4292C12.4272 8.84801 13.8472 8.84201 14.7812 8.83101C15.1312 8.82812 15.4812 8.82112 15.8312 8.81001C15.9513 8.80528 16.0714 8.79727 16.1912 8.78601C16.2138 8.78332 16.236 8.77761 16.2572 8.76901C16.3424 8.72996 16.4169 8.67083 16.4743 8.59668C16.5317 8.52253 16.5702 8.43558 16.5866 8.34326C16.6031 8.25095 16.5969 8.15603 16.5686 8.06664C16.5403 7.97725 16.4907 7.89606 16.4242 7.83001L16.2702 7.67701L16.2412 7.64701H16.2002L10.4302 7.65201C8.91946 7.65038 7.40877 7.65705 5.89815 7.67201C5.42815 7.67901 5.08515 7.68601 4.85015 7.69601C4.73315 7.70101 4.64215 7.70601 4.57415 7.71201C4.52338 7.71471 4.47306 7.7231 4.42415 7.73701L3.43715 24.648ZM12.6092 21.885C12.6632 21.927 12.7292 21.964 12.7942 21.99C12.8554 22.0172 12.9212 22.0328 12.9882 22.036C13.0033 22.0358 13.0182 22.0327 13.0322 22.027C13.1705 21.9656 13.3079 21.9019 13.4442 21.836C13.6912 21.716 14.0352 21.543 14.4442 21.336C15.4399 20.83 16.4332 20.3194 17.4242 19.804C18.4244 19.2856 19.4224 18.7629 20.4182 18.236C20.8322 18.016 21.1832 17.829 21.4372 17.69C21.5708 17.6164 21.7035 17.5411 21.8352 17.464C21.8554 17.4524 21.8747 17.4393 21.8932 17.425C22.0932 17.255 22.1532 16.935 22.0252 16.708C22.0168 16.6939 22.0063 16.6811 21.9942 16.67C21.9556 16.6391 21.9155 16.6101 21.8742 16.583C21.7771 16.5216 21.6788 16.4622 21.5792 16.405C21.2466 16.2128 20.9115 16.0247 20.5742 15.841C19.5759 15.2973 18.5728 14.7622 17.5652 14.236C16.5564 13.7062 15.543 13.1852 14.5252 12.673C14.1783 12.4986 13.8293 12.3286 13.4782 12.163C13.3719 12.1124 13.2645 12.0641 13.1562 12.018C13.1093 11.9986 13.0616 11.9812 13.0132 11.966C12.9988 11.9622 12.984 11.9602 12.9692 11.96C12.8192 11.96 12.6592 12.016 12.5612 12.114C12.5369 12.1368 12.5166 12.1635 12.5012 12.193C12.4815 12.2341 12.468 12.2779 12.4612 12.323C12.4432 12.429 12.4312 12.603 12.4232 12.908C12.4072 13.521 12.4062 14.694 12.4062 16.993V21.725L12.4452 21.755L12.6092 21.885ZM30.1032 5.45901C30.3262 5.63201 30.4702 5.75001 30.5532 5.82701L30.3602 5.87801C29.2296 6.17013 28.0983 6.45913 26.9662 6.74501L23.4012 7.64501L21.9552 6.58801L18.8592 4.32401C18.3342 3.94001 17.9392 3.64301 17.6832 3.43801C17.6002 3.37233 17.5192 3.3043 17.4402 3.23401L17.5832 3.19501L18.3062 3.00501C18.9102 2.84901 19.7312 2.63901 20.6252 2.41401C22.4112 1.96301 24.0172 1.55401 24.1902 1.50501C24.3063 1.47266 24.4233 1.44365 24.5412 1.41801L24.5832 1.44501C24.8804 1.64564 25.1751 1.84999 25.4672 2.05801C26.0422 2.46801 26.8242 3.03201 27.6752 3.65501C28.8842 4.54001 29.6502 5.10801 30.1032 5.45901ZM23.0572 8.84901C23.0892 8.86401 23.1272 8.86701 23.1602 8.86901C23.1962 8.86901 23.2402 8.86601 23.2902 8.85901C23.3942 8.84701 23.5382 8.81901 23.7382 8.77701C24.1382 8.69001 24.7682 8.53501 25.7482 8.28501C26.4332 8.11201 27.0572 7.95701 27.5122 7.84701C27.7167 7.79727 27.9217 7.74927 28.1272 7.70301L28.0982 7.89301C28.0672 8.08601 28.0202 8.35001 27.9652 8.63801C27.8722 9.12701 27.8202 9.38501 27.7672 9.55001C27.7334 9.67078 27.6694 9.78093 27.5812 9.87001C27.4182 10.05 27.1612 10.218 26.8342 10.365C26.4692 10.5229 26.0888 10.6422 25.6992 10.721C24.8572 10.9 23.8972 10.948 23.0762 10.812C21.3392 10.527 19.8262 9.71201 18.9512 8.60401C18.7512 8.35201 18.6662 8.21601 18.6452 8.00201C18.6232 7.77501 18.6752 7.45601 18.7932 6.83601C18.8523 6.52583 18.9156 6.21647 18.9832 5.90801L19.0342 5.94501L19.4732 6.26101C19.8402 6.52801 20.3442 6.89601 20.8952 7.30101C21.4472 7.70701 21.9652 8.08301 22.3532 8.36101C22.5589 8.50844 22.7659 8.65412 22.9742 8.79801C23.0007 8.8164 23.0285 8.8331 23.0572 8.84801V8.84901ZM19.5302 16.64C19.7772 16.773 19.9772 16.881 20.1152 16.958L20.1832 16.995L20.1222 17.029C19.9882 17.103 19.7952 17.207 19.5562 17.334C19.0782 17.589 18.4192 17.936 17.6942 18.314L14.2582 20.108L13.6052 20.448V13.529L14.1622 13.82L17.6002 15.621C18.3522 16.015 19.0352 16.377 19.5302 16.642V16.64ZM1.71515 25.877L1.86515 25.875L2.70815 25.869C7.14081 25.8552 11.5735 25.8485 16.0062 25.849C19.9772 25.849 23.5862 25.852 26.2032 25.859C27.5185 25.862 28.8338 25.8673 30.1492 25.875L30.2982 25.877L30.2372 26.002C30.1012 26.266 29.8532 26.504 29.6472 26.585L29.6362 26.587C29.2372 26.5989 28.8382 26.6076 28.4392 26.613C27.6802 26.621 26.6112 26.629 25.3332 26.634C22.7792 26.646 19.3932 26.652 16.0072 26.652C12.6202 26.652 9.23415 26.646 6.68015 26.634C5.64513 26.6304 4.61013 26.6234 3.57515 26.613C3.19743 26.6082 2.81976 26.6006 2.44215 26.59C2.41678 26.5889 2.39144 26.5873 2.36615 26.585C2.16015 26.505 1.91215 26.265 1.77615 26.002C1.75547 25.9607 1.73447 25.919 1.71515 25.877Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t \u0161kolen\u00ed \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9c4902e\" data-id=\"9c4902e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e31ef7d elementor-widget elementor-widget-heading\" data-id=\"e31ef7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-859557f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"859557f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-97400de\" data-id=\"97400de\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1b9874 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b1b9874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14.952 1.042C8.255 1.682 2.582 6.578 0.951 13.122C0.585 14.59 0.5 15.324 0.5 17.006C0.5 18.688 0.585 19.422 0.95 20.888C2.087 25.448 5.224 29.322 9.46 31.398C11.4446 32.3801 13.6143 32.9315 15.827 33.016C16.655 33.048 16.735 33.041 16.925 32.92C17.445 32.59 17.53 31.959 17.111 31.54L16.885 31.314L16.077 31.263C14.483 31.162 13.431 30.975 12.147 30.566C7.427 29.059 3.737 25.066 2.622 20.257C2.13548 18.117 2.13548 15.895 2.622 13.755C3.822 8.576 8.002 4.378 13.185 3.149C15.3432 2.64175 17.5888 2.63491 19.75 3.129C24.434 4.214 28.378 7.766 29.945 12.31C30.247 13.187 30.474 14.11 30.618 15.049C30.768 16.029 30.767 17.951 30.615 18.991C30.3811 20.5655 29.897 22.0924 29.181 23.514C28.823 24.213 27.996 25.488 27.651 25.875L27.425 26.128L27.423 24.999C27.42 23.98 27.408 23.85 27.293 23.664C26.94 23.094 26.079 23.15 25.762 23.765C25.66 23.962 25.652 24.182 25.667 26.202C25.683 28.332 25.689 28.43 25.814 28.597C25.886 28.693 26.023 28.83 26.119 28.902C26.284 29.025 26.389 29.032 28.261 29.052C30.698 29.078 30.845 29.062 31.149 28.757C31.46 28.445 31.515 28.142 31.329 27.758C31.113 27.314 30.882 27.236 29.772 27.234L28.872 27.233L29.34 26.605C31.008 24.363 32.042 21.797 32.419 18.963C32.542 18.038 32.521 15.684 32.382 14.765C31.89 11.516 30.488 8.563 28.314 6.192C26.6383 4.35671 24.5589 2.93609 22.2399 2.04232C19.921 1.14855 17.426 0.806098 14.952 1.042ZM15.362 6.591C13.592 6.809 11.836 7.478 10.438 8.468C9.67 9.013 8.506 10.177 7.962 10.945C7.189 12.037 6.508 13.59 6.246 14.858C6.192 15.118 6.113 15.708 6.071 16.168C5.946 17.529 6.155 19.173 6.618 20.477C6.887 21.232 7.501 22.415 7.962 23.064C8.506 23.832 9.672 24.997 10.439 25.542C14.797 28.632 20.802 27.933 24.343 23.922C26.825 21.112 27.605 17.238 26.411 13.648C26.141 12.836 25.543 11.661 25.036 10.945C24.491 10.177 23.326 9.012 22.558 8.468C21.864 7.976 20.688 7.373 19.883 7.095C18.584 6.647 16.653 6.432 15.362 6.591ZM18.142 8.481C19.883 8.817 21.358 9.606 22.625 10.877C23.908 12.165 24.671 13.593 25.035 15.393C25.219 16.298 25.215 17.738 25.026 18.639C24.849 19.486 24.428 20.683 24.229 20.909C24.219 20.921 23.943 20.803 23.617 20.647C21.517 19.646 19.445 19.17 16.909 19.107C14.791 19.055 13.125 19.291 11.259 19.907C10.388 20.194 9.288 20.649 9.019 20.833C8.818 20.972 8.748 20.936 8.604 20.619C7.707 18.633 7.574 16.375 8.236 14.337C8.67 13 9.352 11.895 10.37 10.88C11.864 9.391 13.674 8.547 15.835 8.331C16.31 8.284 17.539 8.363 18.142 8.481ZM15.52 10.369C14.845 10.566 14.412 10.822 13.905 11.325C12.407 12.812 12.412 15.083 13.917 16.575C14.387 17.04 15.121 17.442 15.729 17.567C16.3261 17.6876 16.9436 17.6603 17.5278 17.4874C18.1119 17.3144 18.6448 17.0012 19.08 16.575C19.842 15.82 20.187 14.999 20.186 13.943C20.185 12.858 19.869 12.104 19.088 11.323C18.576 10.81 18.08 10.521 17.414 10.348C16.917 10.218 16.004 10.228 15.52 10.369ZM17.153 12.119C17.563 12.259 18.087 12.752 18.264 13.163C18.968 14.8 17.244 16.433 15.642 15.648C14.748 15.211 14.336 14.088 14.732 13.168C14.904 12.767 15.432 12.26 15.819 12.123C16.179 11.996 16.786 11.994 17.153 12.119ZM18.708 21.015C20.121 21.223 21.743 21.709 22.811 22.245L23.284 22.482L22.622 23.139C20.098 25.639 16.412 26.377 13.186 25.029C11.953 24.514 10.62 23.553 9.93 22.682L9.74 22.442L10.216 22.22C11.701 21.524 13.174 21.14 15.299 20.893C15.803 20.834 18.022 20.913 18.708 21.015Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tV\u011brnostn\u00ed program\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-498d701\" data-id=\"498d701\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ec25c elementor-widget elementor-widget-heading\" data-id=\"78ec25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Program Cashback\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c4b229e\" data-id=\"c4b229e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ec8af2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ec8af2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2f99418\" data-id=\"2f99418\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13ca8a2 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"13ca8a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M3.252 0.936001C2.613 1.103 2.147 1.383 1.599 1.927C1.259 2.265 1.078 2.511 0.913 2.858C0.503 3.722 0.5 3.758 0.5 8.432C0.5 13.123 0.503 13.162 0.922 14.012C1.498 15.184 2.882 16.052 4.183 16.056L4.454 16.058V17.35C4.455 18.57 4.464 18.66 4.604 18.961C4.786 19.35 5.164 19.702 5.561 19.854C5.924 19.993 6.608 19.962 6.943 19.793C7.066 19.731 7.775 19.076 8.519 18.337L9.872 16.993L9.892 21.008L9.912 25.023L10.085 25.533C10.634 27.153 11.958 28.267 13.604 28.496C13.904 28.538 15.349 28.565 17.268 28.565H20.437L22.607 30.728C24.017 32.133 24.879 32.943 25.066 33.04C25.301 33.163 25.451 33.19 25.896 33.19C26.36 33.19 26.484 33.165 26.765 33.018C26.9825 32.8937 27.1798 32.7369 27.35 32.553C27.775 32.069 27.81 31.888 27.81 30.117V28.565L28.08 28.564C30.06 28.554 31.695 27.388 32.326 25.534L32.5 25.024V19.63C32.5 13.599 32.522 13.919 32.036 12.93C31.688 12.222 30.899 11.443 30.171 11.089C29.199 10.616 29.405 10.632 24.291 10.632H19.713L19.691 7.234C19.669 3.94 19.665 3.824 19.529 3.422C19.106 2.164 18.069 1.196 16.83 0.904001C16.476 0.821001 15.533 0.808001 10.07 0.810001C4.015 0.812001 3.699 0.819001 3.252 0.936001ZM16.848 2.509C17.297 2.716 17.745 3.169 17.958 3.631L18.142 4.029V10.602L15.685 10.637C12.991 10.677 13.042 10.67 12.209 11.101C11.6034 11.4171 11.0818 11.873 10.6876 12.4309C10.2933 12.9888 10.0377 13.6326 9.942 14.309L9.866 14.826L8.063 16.629C6.753 17.938 6.226 18.425 6.138 18.409C6.025 18.387 6.016 18.289 5.986 16.727C5.943 14.513 5.984 14.578 4.612 14.522C3.751 14.486 3.673 14.472 3.285 14.282C2.81463 14.0567 2.44015 13.6709 2.229 13.194L2.061 12.835V8.464C2.061 4.389 2.069 4.07 2.178 3.757C2.308 3.385 2.815 2.78 3.139 2.611C3.657 2.341 3.57 2.345 10.197 2.357L16.547 2.37L16.848 2.509ZM29.418 12.412C30.193 12.8 30.778 13.567 30.936 14.396C31.023 14.857 31.023 24.281 30.936 24.743C30.783 25.544 30.245 26.291 29.546 26.669C29.086 26.919 28.48 27.031 27.579 27.032C26.883 27.033 26.789 27.047 26.63 27.172C26.298 27.432 26.278 27.57 26.278 29.595C26.278 32.397 26.448 32.405 23.502 29.455C22.274 28.223 21.192 27.175 21.097 27.125C20.953 27.049 20.349 27.033 17.491 27.032C13.743 27.031 13.495 27.012 12.863 26.669C12.165 26.291 11.627 25.544 11.475 24.743C11.387 24.281 11.387 14.858 11.475 14.396C11.5709 13.9179 11.7882 13.4726 12.1061 13.1028C12.424 12.7331 12.8317 12.4515 13.29 12.285C13.595 12.175 14.006 12.169 21.3 12.183L28.99 12.197L29.418 12.412ZM16.004 18.554C15.407 18.792 15.174 19.58 15.524 20.178C15.706 20.486 16.104 20.716 16.458 20.716C16.956 20.716 17.481 20.277 17.573 19.783C17.661 19.314 17.401 18.805 16.955 18.575C16.753 18.47 16.243 18.459 16.005 18.555L16.004 18.554ZM20.79 18.529C20.21 18.746 19.916 19.516 20.2 20.073C20.261 20.193 20.422 20.38 20.557 20.488C20.772 20.66 20.851 20.684 21.205 20.684C21.559 20.684 21.638 20.66 21.853 20.488C22.723 19.792 22.297 18.475 21.205 18.488C21.03 18.491 20.843 18.509 20.79 18.529ZM25.414 18.598C24.607 19.105 24.624 20.157 25.447 20.572C26.223 20.965 27.044 20.442 27.044 19.555C27.044 19.169 26.9 18.887 26.581 18.651C26.326 18.462 25.677 18.432 25.414 18.598Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodpora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0f68f26\" data-id=\"0f68f26\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e08aeff elementor-widget elementor-widget-heading\" data-id=\"e08aeff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">24\/7<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dbd51c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbd51c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35a3201\" data-id=\"35a3201\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20cac79 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"20cac79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"30\" viewBox=\"0 0 37 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M22.837 0.575009C22.771 0.625009 21.638 2.01701 20.319 3.66801C17.729 6.90901 17.731 6.90701 18.098 7.27301C18.269 7.44501 18.312 7.45201 19.258 7.45201H20.242V24.87H21.403V15.77C21.403 6.92301 21.399 6.66401 21.265 6.49701C21.141 6.34401 21.051 6.32201 20.43 6.28901L19.734 6.25301L21.421 4.13301C22.349 2.96801 23.125 2.01401 23.145 2.01401C23.165 2.01401 23.941 2.96801 24.869 4.13401L26.557 6.25401L25.86 6.28901C25.24 6.32201 25.15 6.34401 25.026 6.49701C24.891 6.66401 24.887 6.92301 24.887 15.769V24.87H26.048V7.45101H27.032C27.979 7.45101 28.022 7.44501 28.192 7.27301C28.559 6.90701 28.562 6.90901 25.972 3.66801C24.652 2.01701 23.519 0.625009 23.454 0.575009C23.3613 0.516841 23.2544 0.485354 23.145 0.484009C23.036 0.485237 22.9295 0.517369 22.837 0.575009ZM1.838 15.759L1.66 15.937V26.837L1.838 27.015L2.017 27.194H7.11L7.289 27.015L7.467 26.837V15.937L7.289 15.759L7.11 15.581H2.018L1.838 15.759ZM11.128 15.759L10.951 15.937V26.837L11.129 27.015L11.307 27.194H16.401L16.579 27.015L16.757 26.837V15.937L16.579 15.759L16.401 15.581H11.307L11.128 15.759ZM29.709 16.339L29.531 16.518V26.838L29.709 27.015L29.888 27.194H34.981L35.159 27.015L35.338 26.837V16.517L35.16 16.34L34.981 16.161H29.89L29.711 16.339H29.709ZM6.306 21.388V26.033H2.823V16.743H6.306V21.388ZM15.596 21.388V26.033H12.113V16.743H15.597V21.388H15.596ZM34.177 21.678V26.033H30.693V17.324H34.177V21.678ZM20.242 26.614V27.194H21.403V26.034H20.242V26.614ZM22.564 26.614V27.194H23.725V26.034H22.565V26.614H22.564ZM24.887 26.614V27.194H26.048V26.034H24.888V26.614H24.887ZM0.5 28.936V29.516H36.5V28.355H0.5V28.935V28.936Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tObchodn\u00ed sign\u00e1ly\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f3af81\" data-id=\"1f3af81\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-beacbb0 elementor-widget elementor-widget-heading\" data-id=\"beacbb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Permanentn\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9177366 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9177366\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-322d683\" data-id=\"322d683\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28688b1 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"28688b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"46\" viewBox=\"0 0 33 46\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M15.44 0.294041C14.7806 0.476943 14.177 0.820535 13.683 1.29404C11.991 2.87804 11.92 5.45204 13.522 7.14604C13.781 7.41904 14.145 7.72604 14.331 7.82604L14.669 8.00704V10.655L10.211 10.683C5.891 10.71 5.739 10.717 5.308 10.916C4.354 11.357 3.77 12.142 3.562 13.262L3.454 13.843H2.136C0.983 13.843 0.799 13.865 0.66 14.019C0.516 14.179 0.5 14.666 0.5 19.024V23.854L0.754 24.053C0.981 24.231 1.139 24.253 2.242 24.253H3.476L3.541 24.71C3.60901 25.1982 3.79209 25.6633 4.07515 26.0668C4.3582 26.4704 4.73312 26.8009 5.169 27.031L5.657 27.289L8.427 27.319L11.199 27.348V29.348L7.03 29.378L2.861 29.409L2.258 29.689C1.609 29.988 1.122 30.455 0.769 31.116L0.549 31.53L0.522 38.491C0.495 45.371 0.497 45.455 0.69 45.648C0.885 45.842 0.949 45.843 16.5 45.843C32.051 45.843 32.115 45.843 32.31 45.648C32.503 45.455 32.504 45.371 32.478 38.491L32.452 31.53L32.231 31.116C31.723 30.166 30.974 29.626 29.927 29.454C29.619 29.404 27.665 29.362 25.584 29.362H21.801V27.348L24.572 27.318L27.343 27.288L27.837 27.028C28.727 26.559 29.269 25.758 29.47 24.614L29.534 24.253H30.763C31.86 24.253 32.019 24.231 32.246 24.053L32.5 23.853V19.008C32.5 14.436 32.49 14.153 32.324 14.003C32.178 13.871 31.922 13.843 30.847 13.843H29.547L29.439 13.269C29.236 12.177 28.694 11.421 27.799 10.982L27.247 10.711L22.789 10.683L18.331 10.655V8.00704L18.669 7.82504C18.855 7.72504 19.227 7.41204 19.494 7.12904C20.2192 6.36606 20.6235 5.35366 20.6235 4.30104C20.6235 3.24842 20.2192 2.23602 19.494 1.47304C18.448 0.367041 16.85 -0.0979587 15.44 0.294041ZM17.374 1.65904C18.094 1.87004 18.926 2.70704 19.144 3.44004C19.472 4.54604 19.251 5.42104 18.435 6.23604C17.619 7.05304 16.745 7.27304 15.634 6.94304C14.909 6.72804 14.074 5.89204 13.858 5.16704C13.588 4.25704 13.695 3.51104 14.206 2.75904C14.591 2.19104 14.974 1.88904 15.576 1.68204C16.19 1.46904 16.704 1.46204 17.374 1.65904ZM16.982 9.55404V10.662H16.018V8.44504H16.982V9.55404ZM27.134 12.144C27.535 12.311 27.934 12.784 28.062 13.244C28.198 13.732 28.198 24.267 28.062 24.756C27.934 25.216 27.535 25.689 27.134 25.856C26.875 25.964 24.999 25.988 16.509 25.988C9.441 25.988 6.114 25.955 5.928 25.885C5.542 25.739 5.225 25.422 5.02 24.975C4.853 24.615 4.841 24.232 4.84 19.096C4.839 15.608 4.875 13.471 4.938 13.244C5.063 12.795 5.46 12.315 5.845 12.147C6.285 11.955 26.675 11.951 27.135 12.143L27.134 12.144ZM9.146 14.65C8.74874 14.7948 8.38654 15.0218 8.08308 15.3163C7.77962 15.6107 7.54176 15.9659 7.38506 16.3586C7.22836 16.7513 7.15635 17.1726 7.17374 17.5951C7.19113 18.0175 7.29754 18.4316 7.486 18.81C8.543 20.97 11.742 20.949 12.809 18.775C13.179 18.023 13.194 16.92 12.845 16.211C12.56 15.633 12.023 15.08 11.468 14.793C10.944 14.523 9.695 14.446 9.146 14.65ZM21.869 14.65C21.4717 14.7948 21.1095 15.0218 20.8061 15.3163C20.5026 15.6107 20.2648 15.9659 20.1081 16.3586C19.9514 16.7513 19.8793 17.1726 19.8967 17.5951C19.9141 18.0175 20.0205 18.4316 20.209 18.81C21.265 20.97 24.465 20.949 25.532 18.775C25.902 18.023 25.917 16.92 25.568 16.211C25.283 15.633 24.745 15.08 24.191 14.793C23.667 14.523 22.418 14.446 21.869 14.65ZM3.488 19.048V22.903H1.849V15.193H3.488V19.048ZM31.151 19.048V22.903H29.512V15.193H31.151V19.048ZM11.133 16.184C12.349 17.112 11.663 19.094 10.132 19.076C8.972 19.062 8.224 17.968 8.635 16.89C8.914 16.16 9.432 15.84 10.25 15.892C10.657 15.918 10.88 15.992 11.133 16.184ZM23.819 16.152C24.19 16.416 24.496 17.026 24.496 17.506C24.496 17.903 24.168 18.52 23.818 18.78C23.164 19.265 22.27 19.17 21.685 18.557C21.5135 18.3789 21.3858 18.1634 21.3119 17.9274C21.2381 17.6915 21.22 17.4416 21.2593 17.1975C21.2986 16.9534 21.3941 16.7217 21.5383 16.5209C21.6824 16.32 21.8713 16.1554 22.09 16.04C22.554 15.786 23.38 15.84 23.819 16.152ZM12.033 22.887C11.809 23.134 11.831 23.606 12.076 23.828C12.269 24.003 12.485 24.012 16.5 24.012C20.515 24.012 20.73 24.002 20.924 23.828C21.179 23.598 21.193 23.09 20.95 22.87C20.792 22.727 20.34 22.71 16.483 22.71C12.449 22.71 12.183 22.721 12.033 22.887ZM20.452 28.349V29.361H12.548V27.337H20.452V28.349ZM29.842 30.803C30.273 30.903 30.617 31.134 30.904 31.519C31.099 31.78 31.103 31.892 31.128 38.139L31.155 44.494H25.849V38.027L25.613 37.791L25.376 37.554H7.624L7.387 37.79L7.151 38.027V44.494H1.845L1.871 38.139C1.897 31.892 1.901 31.78 2.096 31.519C2.373 31.149 2.732 30.897 3.114 30.807C3.574 30.699 29.375 30.695 29.842 30.803ZM4.217 31.792C2.73 32.105 2.32 34.078 3.547 35.014C3.822 35.224 4.026 35.289 4.503 35.32C5.279 35.37 5.799 35.106 6.169 34.475C6.974 33.101 5.781 31.462 4.217 31.792ZM27.424 32.008C26.971 32.285 26.524 33.054 26.524 33.554C26.524 34.076 26.973 34.827 27.452 35.108C27.82 35.324 27.965 35.354 28.492 35.32C28.974 35.29 29.177 35.225 29.453 35.014C29.6794 34.8436 29.863 34.6228 29.9894 34.3691C30.1158 34.1155 30.1815 33.8359 30.1813 33.5525C30.1811 33.2691 30.1151 32.9897 29.9883 32.7362C29.8616 32.4827 29.6776 32.2622 29.451 32.092C29.164 31.873 28.982 31.818 28.462 31.792C27.916 31.766 27.768 31.797 27.424 32.008ZM5.037 33.325C5.205 33.639 5.01 33.988 4.666 33.988C4.343 33.988 4.163 33.832 4.163 33.554C4.163 33.277 4.343 33.12 4.66 33.12C4.834 33.12 4.965 33.192 5.037 33.325ZM28.722 33.235C28.7952 33.3253 28.8358 33.4378 28.837 33.554C28.837 33.832 28.657 33.988 28.334 33.988C27.99 33.988 27.795 33.639 27.964 33.325C28.086 33.096 28.53 33.044 28.722 33.235ZM24.5 41.7V44.495H8.5V38.903H24.5V41.7Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRobotick\u00fd syst\u00e9m\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3b48c84\" data-id=\"3b48c84\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f61b43c elementor-widget elementor-widget-heading\" data-id=\"f61b43c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5fba6d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fba6d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-edcc348\" data-id=\"edcc348\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fefa3f elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"4fefa3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"33\" height=\"34\" viewBox=\"0 0 33 34\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M2.15686 5.41495V10.38H1.49886C0.891858 10.38 0.826858 10.393 0.670858 10.55C0.329858 10.891 0.374858 10.972 1.98486 12.907C2.82686 13.92 3.54186 14.718 3.63986 14.755C3.75092 14.7956 3.8728 14.7956 3.98386 14.755C4.08186 14.718 4.79686 13.92 5.63886 12.907C7.24886 10.972 7.29386 10.891 6.95286 10.549C6.79686 10.393 6.73186 10.38 6.12486 10.38H5.46686V0.449951H4.36386V11.145L4.53286 11.315C4.66786 11.449 4.77286 11.483 5.05186 11.483H5.40186L4.63786 12.397C4.21786 12.9 3.84586 13.311 3.81186 13.311C3.77786 13.311 3.40586 12.9 2.98586 12.397L2.22186 11.483H2.57186C2.85186 11.483 2.95586 11.449 3.09086 11.314L3.26086 11.144V0.449951H2.15586V5.41495H2.15686ZM7.70786 0.513951C7.08786 0.665951 6.51786 1.13195 6.22486 1.72595C5.99186 2.19895 5.98586 3.08895 6.21286 3.55595C6.44986 4.04395 6.72986 4.33595 7.20286 4.58895C7.61686 4.81095 7.68286 4.82395 8.48286 4.85095L9.32786 4.88095V9.61295L8.01486 11.887C6.66186 14.229 6.27686 15.033 6.02686 16.039C5.64086 17.591 5.65186 18.1459 6.15686 22.6889C6.42686 25.1269 6.56986 26.691 6.56986 27.222V28.033H6.18786C5.87386 28.033 5.77486 28.0629 5.63586 28.2029L5.46586 28.372V33.212L5.63586 33.38L5.80586 33.5499H16.1599L16.3299 33.38L16.4989 33.2109V28.371L16.3289 28.202C16.1989 28.072 16.0879 28.033 15.8469 28.033C15.6749 28.033 15.5339 28.0159 15.5339 27.9939C15.5339 27.9729 15.7359 27.614 15.9839 27.197C16.7789 25.858 16.9789 25.193 17.0309 23.7229C17.0739 22.5029 16.9989 21.923 16.6779 20.983L16.4479 20.3099H24.4349L24.6049 20.1399L24.7739 19.971V4.87995L25.6189 4.85095C26.4189 4.82395 26.4859 4.81095 26.8979 4.59095C27.3809 4.33095 27.5899 4.11595 27.8609 3.59495C28.0159 3.29595 28.0439 3.15495 28.0449 2.65695C28.0469 2.11995 28.0269 2.03395 27.8119 1.63495C27.5579 1.16395 27.2679 0.884951 26.7759 0.639951L26.4629 0.484951L17.1899 0.473951C12.0879 0.467951 7.82186 0.485951 7.70786 0.513951ZM9.32786 2.65695V3.75995H8.67086C7.89286 3.75995 7.63086 3.66995 7.35486 3.30695C7.18986 3.09095 7.15586 2.97995 7.15586 2.65695C7.15586 2.33995 7.19086 2.22095 7.34086 2.02495C7.62886 1.64795 7.88286 1.55695 8.65586 1.55495L9.32786 1.55395V2.65695ZM23.6549 7.90995L23.6369 14.267L23.1889 14.351C21.0019 14.761 19.2259 16.5359 18.8169 18.7229L18.7329 19.1709L17.3439 19.19L15.9549 19.208L15.9349 16.983C15.9139 14.773 15.9129 14.755 15.7429 14.413C15.5063 13.9538 15.1322 13.5801 14.6729 13.344C14.3889 13.205 14.2229 13.175 13.7419 13.174C13.2339 13.174 13.1069 13.199 12.7919 13.364C12.3749 13.583 11.9369 14.004 11.8119 14.309C11.7119 14.547 11.6989 14.549 11.1899 14.413C11.0039 14.3608 10.8134 14.3267 10.6209 14.311L10.4309 14.31V1.55395H23.6719L23.6549 7.90995ZM26.5289 1.78595C27.0169 2.15795 27.1149 2.82595 26.7529 3.30095C26.4769 3.66195 26.1989 3.75895 25.4369 3.75895H24.7749V1.54095L25.5219 1.56495C26.2219 1.58695 26.2849 1.59995 26.5289 1.78595ZM16.3279 2.72095C14.8949 3.03095 13.8349 3.99095 13.3549 5.41395C13.2619 5.68795 13.2259 5.99395 13.2259 6.51795C13.2259 7.63095 13.5739 8.47995 14.3479 9.25295C15.8349 10.741 18.2669 10.735 19.7629 9.23895C20.9479 8.05395 21.2329 6.34395 20.4969 4.81895C19.8839 3.54395 18.6589 2.74695 17.2239 2.68795C16.8829 2.67295 16.4789 2.68795 16.3279 2.72095ZM18.1849 4.02295C18.8069 4.31295 19.2089 4.70995 19.5179 5.33395C19.7609 5.82695 19.7759 5.89195 19.7759 6.51795C19.7759 7.14295 19.7609 7.20795 19.5179 7.70095C19.2079 8.32795 18.8079 8.71895 18.1679 9.02295C17.7509 9.21995 17.6439 9.24095 17.0519 9.24095C16.4589 9.24095 16.3519 9.22095 15.9359 9.02295C15.2949 8.71895 14.8959 8.32795 14.5859 7.70095C14.3419 7.20895 14.3279 7.14295 14.3279 6.52095C14.3279 5.92495 14.3479 5.81895 14.5459 5.40095C14.8229 4.81695 15.2179 4.38895 15.7319 4.11495C16.2749 3.82495 16.5719 3.75995 17.2069 3.78995C17.6209 3.80995 17.8419 3.86195 18.1849 4.02295ZM27.5329 13.137V18.1019H26.8749C26.2679 18.1019 26.2029 18.1149 26.0469 18.2719C25.7059 18.6129 25.7509 18.6939 27.3609 20.6299C28.2029 21.6419 28.9179 22.4399 29.0159 22.4769C29.1269 22.5176 29.2488 22.5176 29.3599 22.4769C29.4579 22.4399 30.1729 21.6419 31.0149 20.6299C32.6249 18.6939 32.6699 18.6129 32.3289 18.2719C32.1729 18.1149 32.1089 18.1019 31.5009 18.1019H30.8429V8.17195H29.7399V18.867L29.9089 19.037C30.0439 19.171 30.1489 19.2059 30.4279 19.2059H30.7779L30.0139 20.1189C29.5939 20.6219 29.2219 21.033 29.1879 21.033C29.1539 21.033 28.7819 20.6219 28.3619 20.1189L27.5979 19.2059H27.9479C28.2279 19.2059 28.3319 19.1709 28.4679 19.0359L28.6359 18.867V8.17295H27.5329V13.137ZM9.52586 20.177C9.66786 20.292 9.80586 20.309 10.6119 20.309H11.5349V20.861H12.6379V17.992C12.6379 14.796 12.6349 14.822 13.1079 14.461C13.3059 14.31 13.4239 14.275 13.7419 14.275C14.0589 14.275 14.1769 14.31 14.3749 14.461C14.8329 14.811 14.8449 14.8809 14.8449 17.216V19.309L15.2909 20.4319C15.5359 21.0489 15.7839 21.785 15.8429 22.066C15.9749 22.709 15.9789 23.9959 15.8509 24.6639C15.7129 25.3839 15.5329 25.797 14.8739 26.908C14.5539 27.447 14.2939 27.9199 14.2939 27.9599C14.2939 28.0099 13.2509 28.0319 10.9839 28.0319H7.67386V27.1819C7.67386 26.5999 7.54286 25.1549 7.25986 22.6189C6.82586 18.7269 6.78586 18.028 6.94186 17.068C7.15186 15.774 7.38086 15.213 8.48686 13.278L9.29386 11.868L9.32786 15.957L9.36286 20.045L9.52586 20.177ZM11.2359 15.568L11.5009 15.655L11.5189 17.43L11.5369 19.2059H10.4319V15.395L10.7019 15.438C10.8499 15.462 11.0909 15.521 11.2359 15.568ZM23.6719 17.309V19.2059H21.7749C19.6249 19.2059 19.7999 19.2659 19.9809 18.5879C20.2979 17.3969 21.2259 16.296 22.3539 15.773C22.7609 15.585 23.2719 15.429 23.5159 15.419L23.6719 15.413V17.309ZM15.3969 30.79V32.445H6.56986V29.135H15.3969V30.79Z\" fill=\"#37F935\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPodm\u00ednky pro odstoupen\u00ed od smlouvy\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-607bc38\" data-id=\"607bc38\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2445421 elementor-widget elementor-widget-heading\" data-id=\"2445421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bez omezen\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df3c243 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df3c243\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36423a2\" data-id=\"36423a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2781dd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2781dd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9c637d\" data-id=\"f9c637d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddfab80 elementor-widget elementor-widget-image\" data-id=\"ddfab80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1738\" height=\"1516\" src=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1.webp\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1629\" alt=\"\" srcset=\"https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1.webp 1738w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1-768x670.webp 768w, https:\/\/portalinv.org\/wp-content\/uploads\/2023\/07\/FXALL-MetaTrader-xx-for-mobile-1-1536x1340.webp 1536w\" sizes=\"(max-width: 1738px) 100vw, 1738px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a1310b\" data-id=\"7a1310b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25923d0 elementor-widget elementor-widget-heading\" data-id=\"25923d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> 4 kroky pro registraci na port\u00e1lu Invest Trade <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1516529 elementor-widget elementor-widget-text-editor\" data-id=\"1516529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Na\u0161e r\u016fzn\u00e9 typy exekuc\u00ed jsou pokro\u010dil\u00e9 a zaji\u0161\u0165uj\u00ed v\u00e1m nejni\u017e\u0161\u00ed mo\u017en\u00e9 plovouc\u00ed sazby. Poskytujeme flexibiln\u00ed rozsah p\u00e1kov\u00e9ho efektu v z\u00e1vislosti na typu \u00fa\u010dtu, kter\u00fd si vyberete.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e8b5e9 elementor-widget elementor-widget-toggle\" data-id=\"7e8b5e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1321\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1321\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Registrace<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1321\"><p><span style=\"font-weight: 400;\">Vyberte si pl\u00e1n \u00fa\u010dtu a zaregistrujte se pomoc\u00ed sv\u00e9ho jm\u00e9na a e-mailov\u00e9 adresy.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1322\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1322\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ov\u011b\u0159ov\u00e1n\u00ed<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1322\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1322\"><p><span style=\"font-weight: 400;\">P\u0159idajte pot\u0159ebn\u00e9 doklady k prok\u00e1z\u00e1n\u00ed toto\u017enosti a ov\u011b\u0159it je v mezin\u00e1rodn\u00edm finan\u010dn\u00edm syst\u00e9mu v souladu s pravidly finan\u010dn\u00edch trh\u016f.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1323\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1323\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Financov\u00e1n\u00ed<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1323\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1323\"><p><span style=\"font-weight: 400;\">Aktivujte sv\u016fj \u00fa\u010det a za\u010dn\u011bte obchodovat od pouh\u00fdch 250 \u20ac<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1324\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1324\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Obchodov\u00e1n\u00ed<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1324\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1324\"><p><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">P\u0159ihlaste se a za\u010dn\u011bte obchodovat v\u00edce ne\u017e 200 n\u00e1stroj\u016f!<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00da\u010dty Port\u00e1l Invest Trade Otev\u0159en\u00fd \u00fa\u010det Test 250\u20ac Basic 3000\u20ac Standard 10 000\u20ac Standard+ 25 000\u20ac Advanced 50 000\u20ac Pro Account 100 000\u20ac Vip 250 000\u20ac Test 250\u20ac Leverage 1 : 100 Minimum spread 2.6 points Expert support 7 days Trust management No Assets Currency pairs Expert Commission 5% Video training Yes Loyalty program From [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-901","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages\/901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/comments?post=901"}],"version-history":[{"count":22,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages\/901\/revisions"}],"predecessor-version":[{"id":1563,"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/pages\/901\/revisions\/1563"}],"wp:attachment":[{"href":"https:\/\/portalinv.org\/cs\/wp-json\/wp\/v2\/media?parent=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}